{"id":15976,"date":"2016-03-25T13:22:35","date_gmt":"2016-03-25T13:22:35","guid":{"rendered":"https:\/\/informnapalm.org\/de\/?p=15976"},"modified":"2016-03-25T13:42:48","modified_gmt":"2016-03-25T13:42:48","slug":"russland-verstaerkt-seine-truppen-im-rostower-gebiet","status":"publish","type":"post","link":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/","title":{"rendered":"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Die internationale Freiwilligengemeinschaft InformNapalm beobachtet weiterhin die Situation in den an die Ukraine angrenzenden Basislagern der Rostower Gruppierung russischer Streitkr\u00e4fte, die auf Donbass ausgerichtet ist.\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Mit Fr\u00fchlingsbeginn wird verst\u00e4rkte Aktivit\u00e4t beim Transport von milit\u00e4rischer Fracht im Rostower Gebiet beobachtet, wie per Eisenbahn so auch per Autobahn. Dabei geht es nicht nur um Milit\u00e4rger\u00e4t, sondern auch\u00a0um die Verlegung von mehreren frischen zusammengesetzten taktischen Gruppen aus einigen Truppenverb\u00e4nden der russischen Landstreitkr\u00e4fte, sowohl aus dem S\u00fcdlichen als auch aus anderen Milit\u00e4rbezirken.\u00a0<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify\">Unter den Neuangekommenen wurde eine bataillon-taktische Gruppe aus dem Bestand der <strong>136. selbstst\u00e4ndigen motorisierten Sch\u00fctzenbrigade<\/strong> (Einheit 69671, Bujnaksk, Dagestan, S\u00fcdlicher Milit\u00e4rbezirk) registriert. Derzeitiger Standort dieser bataillon-taktischen Gruppe liegt im Raum des Kusminski Truppen\u00fcbungsplatzes im Mjasnikowski Bezirk des Rostower Gebiets. Unserer Einsch\u00e4tzung nach besteht die zusammengesetzte taktische Gruppe aus dem 3. motorisierten Sch\u00fctzenbataillon mit SPWs, einem Aufkl\u00e4rungszug (Truppenaufkl\u00e4rung und Scharfsch\u00fctzen mit BTR), einer verst\u00e4rkten Panzerkompanie (circa 15 Einheiten T-90), einer zusammengesetzten Raketenartilleriedivision (3-4 Batterien von\u00a0152 mm SFL &#8222;Akazija&#8220; und Raketenwerfern &#8222;Grad&#8220;), wie auch Luftabwehr-Mitteln und anderen Logistik-Abteilungen.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/9-4.jpg\" rel=\"attachment wp-att-21495\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21495 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/9-4.jpg\" alt=\"9\" width=\"709\" height=\"572\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/2-4.jpg\" rel=\"attachment wp-att-21496\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21496 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/2-4.jpg\" alt=\"2\" width=\"888\" height=\"637\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/1-6.jpg\" rel=\"attachment wp-att-21497\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21497 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/1-6.jpg\" alt=\"1\" width=\"701\" height=\"605\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/8-5.jpg\" rel=\"attachment wp-att-21498\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21498 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/8-5.jpg\" alt=\"8\" width=\"687\" height=\"585\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/6-2.jpg\" rel=\"attachment wp-att-21499\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21499 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/6-2.jpg\" alt=\"6\" width=\"681\" height=\"586\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/7-3.jpg\" rel=\"attachment wp-att-21500\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21500 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/7-3.jpg\" alt=\"7\" width=\"680\" height=\"597\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/4-5.jpg\" rel=\"attachment wp-att-21501\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21501 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/4-5.jpg\" alt=\"4\" width=\"698\" height=\"587\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/5-4.jpg\" rel=\"attachment wp-att-21503\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21503 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/5-4.jpg\" alt=\"5\" width=\"948\" height=\"589\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Wie immer, besitzt die ganze russische Milit\u00e4rtechnik weder irgendwelche\u00a0Bordnummern noch Identifikationzeichen. Unter den SPWs mit standardm\u00e4ssiger Khaki-Farbe sieht man interessanterweise einen Wagen in sandiger Farbe (Bild 3 und 5), der h\u00f6chstwahrscheinlich f\u00fcr die Verlegung nach Syrien vorbereitet wurde. Nach Erfordernis der Umst\u00e4nde wurde der Wagen wohl aber in den Bestand der rostower Gruppierung aufgenommen.<\/p>\n<ul>\n<li style=\"text-align: justify\">Dies ist nicht die einzige frischangekommene Abteilung. Ausser den Truppenverb\u00e4nden aus dem S\u00fcdlichen Milit\u00e4rbezirk werden ins Rostower Gebiet auch Abteilungen aus anderen Milit\u00e4rbezirken verlegt. Im besonderen wurde die Verlegung von schweren Mehrfachraketenwerfern <strong>9P140 &#8222;Uragan&#8220;<\/strong> aus dem Bestand der <strong>338. Raketenartilleriebrigade<\/strong> (Einheit 57637, Nowosysojewka, Primorskij Region, \u00d6stlicher Milit\u00e4rbezirk) registriert. Unserer Einsch\u00e4tzung nach ist es zumindest eine Raketendivision (6 SPWs).<\/li>\n<\/ul>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/07.jpg\" rel=\"attachment wp-att-21509\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21509 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/07.jpg\" alt=\"07\" width=\"713\" height=\"609\" \/><\/a><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/06.jpg\" rel=\"attachment wp-att-21510\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21510 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/06.jpg\" alt=\"06\" width=\"718\" height=\"592\" \/><\/a><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/03.jpg\" rel=\"attachment wp-att-21511\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21511 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/03.jpg\" alt=\"03\" width=\"684\" height=\"597\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/02.jpg\" rel=\"attachment wp-att-21514\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21514 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/02.jpg\" alt=\"02\" width=\"699\" height=\"598\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/04.jpg\" rel=\"attachment wp-att-21512\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21512 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/04.jpg\" alt=\"04\" width=\"944\" height=\"608\" \/><\/a><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/01.jpg\" rel=\"attachment wp-att-21513\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21513 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/01.jpg\" alt=\"01\" width=\"708\" height=\"638\" \/><\/a><\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/05.jpg\" rel=\"attachment wp-att-21515\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21515 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/05.jpg\" alt=\"05\" width=\"690\" height=\"594\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Logischerweise nehmen wir an, dass dies nicht die einzige Abteilung aus dem \u00d6stlichen Milit\u00e4rbezirk ist, die aus dem Fernen Osten Russlands zur Grenze mit der Ukraine verlegt worden ist. Zum Beispiel sieht man auf dem dritten Bild einen Zug beladen mit <strong>Flugabwehrpanzern &#8222;Schilka&#8220;<\/strong>, der allem Anschein nach in den S\u00fcden von Russland f\u00e4hrt. Die OSINT-Gruppe f\u00fchrt noch zus\u00e4tzliche Aufkl\u00e4rung durch und \u00fcber weitere identifizierte Abteilungen werden wir sp\u00e4ter berichten.<\/p>\n<p style=\"text-align: justify\">Wir m\u00f6chten daran erinnern, dass der Truppen\u00fcbungsplatz Kadamowski im Mjasnikwoski Bezirk nicht nur eine der Hauptbasen f\u00fcr die Truppen und Mittel der rostower Gruppierung darstellt, sondern auch ein Aufmarschgebiet f\u00fcr ihre weitere Verlegung in den Donbass ist, was in unseren fr\u00fcheren Untersuchungen mehrmals bewiesen wurde.<\/p>\n<p style=\"text-align: justify\">Wir haben die\u00a0Gesichter auf den Fotos mit Absicht unkenntlich gemacht, um die Arbeit der russischen Geheimdienste zu erschweren, die mit der L\u00f6schung von Quellen des Informationsleaks besch\u00e4ftigt sind.<\/p>\n<hr \/>\n<p>Datenbasis mit Untersuchungen von InformNapalm zu \u00fcber 61 Truppenverb\u00e4nden der Streitkr\u00e4fte Russlands, die sich am Krieg im Donbass beteiligen, unter folgendem Link: <strong><a href=\"http:\/\/bit.ly\/RussianPresence\">http:\/\/bit.ly\/RussianPresence<\/a><\/strong> (in 12 Sprachen) und <strong><a href=\"http:\/\/bit.ly\/RussianPresence\/DE\">http:\/\/bit.ly\/RussianPresence\/DE<\/a><\/strong> (auf Deutsch)<\/p>\n<p><em>Dieses Material wurde von <a href=\"https:\/\/www.facebook.com\/irakli.komaxidze\"><strong>Irakli Komakhidze<\/strong><\/a>\u00a0exklusiv f\u00fcr <a href=\"https:\/\/informnapalm.org\/21274-rossiya-usilivaet-gruppirovku\/\">InformNapalm<\/a> vorbereitet; \u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/Kaspijka\">Irina Schlegel<\/a>. <strong>Beim Nachdruck und Verwenden des Materials ist ein Hinweis auf unsere Ressource erforderlich.<\/strong><\/em><\/p>\n<p><em><strong>CC BY 4.0<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die internationale Freiwilligengemeinschaft InformNapalm beobachtet weiterhin die Situation in den an die Ukraine angrenzenden Basislagern der Rostower&#8230;<\/p>\n","protected":false},"author":121,"featured_media":15980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[98,228,1],"tags":[466,782,9,634,530],"class_list":["post-15976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-informnapalm-eilmeldungen","category-beweise","tag-466","tag-782","tag-donbass","tag-kadamowski","tag-rostower-gebiet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Russland verst\u00e4rkt seine Truppen im Rostower Gebiet - InformNapalm (Deutsch)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet - InformNapalm (Deutsch)\" \/>\n<meta property=\"og:description\" content=\"Die internationale Freiwilligengemeinschaft InformNapalm beobachtet weiterhin die Situation in den an die Ukraine angrenzenden Basislagern der Rostower...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/\" \/>\n<meta property=\"og:site_name\" content=\"InformNapalm (Deutsch)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/informnapalm24\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-25T13:22:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-25T13:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/02\/wir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kaspijka\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"kaspijka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/\"},\"author\":{\"name\":\"kaspijka\",\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/1a18fa737cbf9480a979b71b479acb87\"},\"headline\":\"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet\",\"datePublished\":\"2016-03-25T13:22:35+00:00\",\"dateModified\":\"2016-03-25T13:42:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/\"},\"wordCount\":535,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg\",\"keywords\":[\"136.\",\"338.\",\"Donbass\",\"Kadamowski\",\"Rostower Gebiet\"],\"articleSection\":[\"Aktuell\",\"InformNapalm\",\"Photo und Videobeweise\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/\",\"url\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/\",\"name\":\"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet - InformNapalm (Deutsch)\",\"isPartOf\":{\"@id\":\"https:\/\/informnapalm.org\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg\",\"datePublished\":\"2016-03-25T13:22:35+00:00\",\"dateModified\":\"2016-03-25T13:42:48+00:00\",\"author\":{\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/1a18fa737cbf9480a979b71b479acb87\"},\"breadcrumb\":{\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage\",\"url\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg\",\"contentUrl\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg\",\"width\":642,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/informnapalm.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/informnapalm.org\/de\/#website\",\"url\":\"https:\/\/informnapalm.org\/de\/\",\"name\":\"InformNapalm (Deutsch)\",\"description\":\"OSINT, HUMINT, Analytik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/informnapalm.org\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/1a18fa737cbf9480a979b71b479acb87\",\"name\":\"kaspijka\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/72af308a9fedfea91400c3b24df379a1f9b25075f50b569c226bec03a4b2ccc6?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/72af308a9fedfea91400c3b24df379a1f9b25075f50b569c226bec03a4b2ccc6?s=96&d=blank&r=g\",\"caption\":\"kaspijka\"},\"url\":\"https:\/\/informnapalm.org\/de\/author\/kaspijka\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet - InformNapalm (Deutsch)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/","og_locale":"de_DE","og_type":"article","og_title":"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet - InformNapalm (Deutsch)","og_description":"Die internationale Freiwilligengemeinschaft InformNapalm beobachtet weiterhin die Situation in den an die Ukraine angrenzenden Basislagern der Rostower...","og_url":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/","og_site_name":"InformNapalm (Deutsch)","article_publisher":"https:\/\/www.facebook.com\/informnapalm24","article_published_time":"2016-03-25T13:22:35+00:00","article_modified_time":"2016-03-25T13:42:48+00:00","og_image":[{"width":1000,"height":650,"url":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/02\/wir.jpg","type":"image\/jpeg"}],"author":"kaspijka","twitter_misc":{"Verfasst von":"kaspijka","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#article","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/"},"author":{"name":"kaspijka","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/1a18fa737cbf9480a979b71b479acb87"},"headline":"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet","datePublished":"2016-03-25T13:22:35+00:00","dateModified":"2016-03-25T13:42:48+00:00","mainEntityOfPage":{"@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/"},"wordCount":535,"commentCount":0,"image":{"@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg","keywords":["136.","338.","Donbass","Kadamowski","Rostower Gebiet"],"articleSection":["Aktuell","InformNapalm","Photo und Videobeweise"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/","url":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/","name":"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet - InformNapalm (Deutsch)","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage"},"image":{"@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg","datePublished":"2016-03-25T13:22:35+00:00","dateModified":"2016-03-25T13:42:48+00:00","author":{"@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/1a18fa737cbf9480a979b71b479acb87"},"breadcrumb":{"@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#primaryimage","url":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg","contentUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/03\/Teq-dFI4Y3w-642x336.jpg","width":642,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/informnapalm.org\/de\/russland-verstaerkt-seine-truppen-im-rostower-gebiet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/informnapalm.org\/de\/"},{"@type":"ListItem","position":2,"name":"Russland verst\u00e4rkt seine Truppen im Rostower Gebiet"}]},{"@type":"WebSite","@id":"https:\/\/informnapalm.org\/de\/#website","url":"https:\/\/informnapalm.org\/de\/","name":"InformNapalm (Deutsch)","description":"OSINT, HUMINT, Analytik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informnapalm.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/1a18fa737cbf9480a979b71b479acb87","name":"kaspijka","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/72af308a9fedfea91400c3b24df379a1f9b25075f50b569c226bec03a4b2ccc6?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72af308a9fedfea91400c3b24df379a1f9b25075f50b569c226bec03a4b2ccc6?s=96&d=blank&r=g","caption":"kaspijka"},"url":"https:\/\/informnapalm.org\/de\/author\/kaspijka\/"}]}},"views":2671,"post_src":"<p style=\"text-align: justify\"><strong>Die internationale Freiwilligengemeinschaft InformNapalm beobachtet weiterhin die Situation in den an die Ukraine angrenzenden Basislagern der Rostower Gruppierung russischer Streitkr\u00e4fte, die auf Donbass ausgerichtet ist.\u00a0<\/strong><\/p>\r\n<p style=\"text-align: justify\"><strong>Mit Fr\u00fchlingsbeginn wird verst\u00e4rkte Aktivit\u00e4t beim Transport von milit\u00e4rischer Fracht im Rostower Gebiet beobachtet, wie per Eisenbahn so auch per Autobahn. Dabei geht es nicht nur um Milit\u00e4rger\u00e4t, sondern auch\u00a0um die Verlegung von mehreren frischen zusammengesetzten taktischen Gruppen aus einigen Truppenverb\u00e4nden der russischen Landstreitkr\u00e4fte, sowohl aus dem S\u00fcdlichen als auch aus anderen Milit\u00e4rbezirken.\u00a0<\/strong><\/p>\r\n\r\n<ul>\r\n\t<li style=\"text-align: justify\">Unter den Neuangekommenen wurde eine bataillon-taktische Gruppe aus dem Bestand der <strong>136. selbstst\u00e4ndigen motorisierten Sch\u00fctzenbrigade<\/strong> (Einheit 69671, Bujnaksk, Dagestan, S\u00fcdlicher Milit\u00e4rbezirk) registriert. Derzeitiger Standort dieser bataillon-taktischen Gruppe liegt im Raum des Kusminski Truppen\u00fcbungsplatzes im Mjasnikowski Bezirk des Rostower Gebiets. Unserer Einsch\u00e4tzung nach besteht die zusammengesetzte taktische Gruppe aus dem 3. motorisierten Sch\u00fctzenbataillon mit SPWs, einem Aufkl\u00e4rungszug (Truppenaufkl\u00e4rung und Scharfsch\u00fctzen mit BTR), einer verst\u00e4rkten Panzerkompanie (circa 15 Einheiten T-90), einer zusammengesetzten Raketenartilleriedivision (3-4 Batterien von\u00a0152 mm SFL \"Akazija\" und Raketenwerfern \"Grad\"), wie auch Luftabwehr-Mitteln und anderen Logistik-Abteilungen.<\/li>\r\n<\/ul>\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/9-4.jpg\" rel=\"attachment wp-att-21495\"><img class=\"alignnone wp-image-21495 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/9-4.jpg\" alt=\"9\" width=\"709\" height=\"572\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/2-4.jpg\" rel=\"attachment wp-att-21496\"><img class=\"alignnone wp-image-21496 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/2-4.jpg\" alt=\"2\" width=\"888\" height=\"637\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/1-6.jpg\" rel=\"attachment wp-att-21497\"><img class=\"alignnone wp-image-21497 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/1-6.jpg\" alt=\"1\" width=\"701\" height=\"605\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/8-5.jpg\" rel=\"attachment wp-att-21498\"><img class=\"alignnone wp-image-21498 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/8-5.jpg\" alt=\"8\" width=\"687\" height=\"585\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/6-2.jpg\" rel=\"attachment wp-att-21499\"><img class=\"alignnone wp-image-21499 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/6-2.jpg\" alt=\"6\" width=\"681\" height=\"586\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/7-3.jpg\" rel=\"attachment wp-att-21500\"><img class=\"alignnone wp-image-21500 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/7-3.jpg\" alt=\"7\" width=\"680\" height=\"597\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/4-5.jpg\" rel=\"attachment wp-att-21501\"><img class=\"alignnone wp-image-21501 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/4-5.jpg\" alt=\"4\" width=\"698\" height=\"587\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/5-4.jpg\" rel=\"attachment wp-att-21503\"><img class=\"alignnone wp-image-21503 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/5-4.jpg\" alt=\"5\" width=\"948\" height=\"589\" \/><\/a>\r\n<p style=\"text-align: justify\">Wie immer, besitzt die ganze russische Milit\u00e4rtechnik weder irgendwelche\u00a0Bordnummern noch Identifikationzeichen. Unter den SPWs mit standardm\u00e4ssiger Khaki-Farbe sieht man interessanterweise einen Wagen in sandiger Farbe (Bild 3 und 5), der h\u00f6chstwahrscheinlich f\u00fcr die Verlegung nach Syrien vorbereitet wurde. Nach Erfordernis der Umst\u00e4nde wurde der Wagen wohl aber in den Bestand der rostower Gruppierung aufgenommen.<\/p>\r\n\r\n<ul>\r\n\t<li style=\"text-align: justify\">Dies ist nicht die einzige frischangekommene Abteilung. Ausser den Truppenverb\u00e4nden aus dem S\u00fcdlichen Milit\u00e4rbezirk werden ins Rostower Gebiet auch Abteilungen aus anderen Milit\u00e4rbezirken verlegt. Im besonderen wurde die Verlegung von schweren Mehrfachraketenwerfern <strong>9P140 \"Uragan\"<\/strong> aus dem Bestand der <strong>338. Raketenartilleriebrigade<\/strong> (Einheit 57637, Nowosysojewka, Primorskij Region, \u00d6stlicher Milit\u00e4rbezirk) registriert. Unserer Einsch\u00e4tzung nach ist es zumindest eine Raketendivision (6 SPWs).<\/li>\r\n<\/ul>\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/07.jpg\" rel=\"attachment wp-att-21509\"><img class=\"alignnone wp-image-21509 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/07.jpg\" alt=\"07\" width=\"713\" height=\"609\" \/><\/a><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/06.jpg\" rel=\"attachment wp-att-21510\"><img class=\"alignnone wp-image-21510 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/06.jpg\" alt=\"06\" width=\"718\" height=\"592\" \/><\/a><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/03.jpg\" rel=\"attachment wp-att-21511\"><img class=\"alignnone wp-image-21511 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/03.jpg\" alt=\"03\" width=\"684\" height=\"597\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/02.jpg\" rel=\"attachment wp-att-21514\"><img class=\"alignnone wp-image-21514 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/02.jpg\" alt=\"02\" width=\"699\" height=\"598\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/04.jpg\" rel=\"attachment wp-att-21512\"><img class=\"alignnone wp-image-21512 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/04.jpg\" alt=\"04\" width=\"944\" height=\"608\" \/><\/a><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/01.jpg\" rel=\"attachment wp-att-21513\"><img class=\"alignnone wp-image-21513 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/01.jpg\" alt=\"01\" width=\"708\" height=\"638\" \/><\/a>\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/05.jpg\" rel=\"attachment wp-att-21515\"><img class=\"alignnone wp-image-21515 size-full\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2016\/03\/05.jpg\" alt=\"05\" width=\"690\" height=\"594\" \/><\/a>\r\n<p style=\"text-align: justify\">Logischerweise nehmen wir an, dass dies nicht die einzige Abteilung aus dem \u00d6stlichen Milit\u00e4rbezirk ist, die aus dem Fernen Osten Russlands zur Grenze mit der Ukraine verlegt worden ist. Zum Beispiel sieht man auf dem dritten Bild einen Zug beladen mit <strong>Flugabwehrpanzern \"Schilka\"<\/strong>, der allem Anschein nach in den S\u00fcden von Russland f\u00e4hrt. Die OSINT-Gruppe f\u00fchrt noch zus\u00e4tzliche Aufkl\u00e4rung durch und \u00fcber weitere identifizierte Abteilungen werden wir sp\u00e4ter berichten.<\/p>\r\n<p style=\"text-align: justify\">Wir m\u00f6chten daran erinnern, dass der Truppen\u00fcbungsplatz Kadamowski im Mjasnikwoski Bezirk nicht nur eine der Hauptbasen f\u00fcr die Truppen und Mittel der rostower Gruppierung darstellt, sondern auch ein Aufmarschgebiet f\u00fcr ihre weitere Verlegung in den Donbass ist, was in unseren fr\u00fcheren Untersuchungen mehrmals bewiesen wurde.<\/p>\r\n<p style=\"text-align: justify\">Wir haben die\u00a0Gesichter auf den Fotos mit Absicht unkenntlich gemacht, um die Arbeit der russischen Geheimdienste zu erschweren, die mit der L\u00f6schung von Quellen des Informationsleaks besch\u00e4ftigt sind.<\/p>\r\n\r\n\r\n<hr \/>\r\n\r\nDatenbasis mit Untersuchungen von InformNapalm zu \u00fcber 61 Truppenverb\u00e4nden der Streitkr\u00e4fte Russlands, die sich am Krieg im Donbass beteiligen, unter folgendem Link: <strong><a href=\"http:\/\/bit.ly\/RussianPresence\">http:\/\/bit.ly\/RussianPresence<\/a><\/strong> (in 12 Sprachen) und <strong><a href=\"http:\/\/bit.ly\/RussianPresence\/DE\">http:\/\/bit.ly\/RussianPresence\/DE<\/a><\/strong> (auf Deutsch)\r\n\r\n<em>Dieses Material wurde von <a href=\"https:\/\/www.facebook.com\/irakli.komaxidze\"><strong>Irakli Komakhidze<\/strong><\/a>\u00a0exklusiv f\u00fcr <a href=\"https:\/\/informnapalm.org\/21274-rossiya-usilivaet-gruppirovku\/\">InformNapalm<\/a> vorbereitet; \u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/Kaspijka\">Irina Schlegel<\/a>. <strong>Beim Nachdruck und Verwenden des Materials ist ein Hinweis auf unsere Ressource erforderlich.<\/strong><\/em>\r\n\r\n<em><strong>CC BY 4.0<\/strong><\/em>\r\n\r\n&nbsp;","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/15976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/users\/121"}],"replies":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/comments?post=15976"}],"version-history":[{"count":5,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/15976\/revisions"}],"predecessor-version":[{"id":15983,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/15976\/revisions\/15983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/media\/15980"}],"wp:attachment":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/media?parent=15976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/categories?post=15976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/tags?post=15976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}