{"id":16895,"date":"2016-04-30T08:38:38","date_gmt":"2016-04-30T08:38:38","guid":{"rendered":"https:\/\/informnapalm.org\/de\/?p=16895"},"modified":"2016-04-30T08:38:38","modified_gmt":"2016-04-30T08:38:38","slug":"russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets","status":"publish","type":"post","link":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/","title":{"rendered":"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets"},"content":{"rendered":"<p>Am 20. April 2016 besuchten hohe Milit\u00e4rbeamte den S\u00fcdlichen Milit\u00e4rbezirk der Russischen F\u00f6deration. Der erste russische stellvertretende Verteidigungsminister, Armeegeneral Ruslan Zalikow und der stellvertretende russische Verteidigungsminister, Armeegeneral Dmitri Bulgakow reisten zur Inspektion in die Gebiete Woronesch und Rostow. Das Ziel des Besuchs war die Durchf\u00fchrung der Kontrolle des Bauablaufs der zweigleisigen elektrischen Eisenbahnlinie, deren Baubeginn vor einem Jahr am 25. April 2015 zur Umgehung der Ukraine im Bereich Zhurawka \u2013 Millerowo war.<\/p>\n<p align=\"JUSTIFY\"><a href=\"http:\/\/wikimapia.org\/#lang=en&amp;lat=49.774613&amp;lon=39.806213&amp;z=11&amp;m=b&amp;show=\/32870873\/ru\/\u041f\u0435\u0440\u0432\u044b\u0439-\u0441\u0442\u0440\u043e\u044f\u0449\u0438\u0439\u0441\u044f-\u0443\u0447\u0430\u0441\u0442\u043e\u043a-\u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0439-\u0434\u043e\u0440\u043e\u0433\u0438-\u0432-\u043e\u0431\u0445\u043e\u0434-\u0423\u043a\u0440\u0430\u0438\u043d\u044b\">F\u00fcr die erste und zweite Bauetappe<\/a> waren die Erdaufbereitung und der Eisenbahnuntergrundbau auf einem Abschnitt von 11 bis 52,4 Kilometer vorgesehen. Diese Arbeiten wurden 2015 abgeschlossen.<\/p>\n<p align=\"JUSTIFY\">Einen Teilabschnitt des Eisenbahnuntergrundes ab der Station Zhurawka bis zur Station Nowopavlowka kann man <a href=\"https:\/\/browse.digitalglobe.com\/imagefinder\/showBrowseMetadata?csrfToken=mJ0H7dGhlpIRARl6dRY9bg36OIsTcFY%2Fegse50fmdU5lYJ0Hd6GvAifVpfzEHK5Gc%2BOj%2Bi32z%2BVy4eFC7ODuhB%2B6K5J4KM3AlEObDwLAFPbK%2FtkT77BIpWljSGZdZLxzNJHGOc9tCIFk%2B9wtsQzNoVtjKPVLnWmaraZuEuIzRAzaPs6849C98B5t8OFusDY54a3J2z87s4zGsVf0dTUiXycb%2FGHVc50PY1FQcdhhvkuJq83T1BVVkNCQWijLIyOO9kh4fN2ZsF7XyUDVECnxoDY68w%2BJ1ODavToEw%2BodqPHLJahHRIqWnnoeRO2ptjDwZZ%2BBhKEs0Jxfkh0JteTNKA%3D%3D&amp;buffer=1.0&amp;catalogId=10400100174B4900&amp;imageHeight=natres&amp;imageWidth=natres\">auf dem Satellitenbild vom 11. Januar 2016<\/a> von DigitalGlobe erkennen. Leider wurden auf anderen Karten die Satellitenaufnahmen dieses Gebietes bislang noch nicht aktualisiert und wir k\u00f6nnen uns nicht vergewissern, bis zum welchen Punkt der Bahndamm tats\u00e4chlich errichtet wurde.<\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16900\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3.jpg\" alt=\"Kantemirovka-3\" width=\"1348\" height=\"643\" srcset=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3.jpg 1348w, https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3-300x143.jpg 300w, https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3-768x366.jpg 768w, https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3-1024x488.jpg 1024w\" sizes=\"auto, (max-width: 1348px) 100vw, 1348px\" \/><\/a><\/p>\n<p>F\u00fcr die Durchf\u00fchrung der geplanten Arbeiten werden Soldaten der Eisenbahntruppen herangezogen, die in regelm\u00e4\u00dfigen Abst\u00e4nden durch den Dreck waten und die Technik aus dem Sumpf holen. Die Arbeiten werden auch in der Winterzeit verrichtet. In den Sozialnetzwerkprofilen der Soldaten gelang es einige Aufnahmen von der Baustelle ausfindig zu machen.<\/p>\n<p><a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16901\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1.jpg\" alt=\"Technik-1\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1.jpg 2560w, https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1-300x225.jpg 300w, https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1-768x576.jpg 768w, https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-16899 alignnone\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-2.jpg\" alt=\"Kantemirovka-2\" width=\"280\" height=\"251\" \/><\/a> <a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-16898 alignnone\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka.jpg\" alt=\"Kantemirovka\" width=\"267\" height=\"254\" srcset=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka.jpg 626w, https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-300x284.jpg 300w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/><\/a><\/p>\n<p align=\"JUSTIFY\">Laut den Medien haben die Gener\u00e4le Zalikow und Bulgakow w\u00e4hrend ihres Besuch den Startschuss f\u00fcr die Verlegung des Gleisrostes <a href=\"http:\/\/www.vesti.ru\/doc.html?id=2745229\">gegeben<\/a>, indem sie m<strong>it Schraubenschl\u00fcsseln die Bolzen auf die Verbindungsstellen zweier Gleisverbindungen im Bereich Zhurawka \u2013 Millerowo gedreht haben<\/strong>. Die weitere Verlegung des Gleisrostes werden Spezialisten-Streckenbauer der Eisenbahntruppen der offenen Aktiengesellschaft Russian Railways durchf\u00fchren.<\/p>\n<p align=\"JUSTIFY\">In sowjetischer Tradition wird die Fertigstellung jeder Bauetappe bei den Soldaten mit Meldungen von der Unterbietung der Baufristen begleitet. Seit Baubeginn ist genau ein Jahr vergangen, vollst\u00e4ndig sind jedoch lediglich zwei Etappen abgeschlossen. Zum jetzigen Zeitpunkt sind die Eisenbahntruppen nur bis an die Grenzen des russischen Gebietes Rostow vorangekommen und weiter stehen der schwierige Bau einer Br\u00fccke \u00fcber den Fluss Kalitwa und der nicht k\u00fcrzerer Abschnitt bis nach Millerowo auf dem Plan.<\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/800px-Shema_I_ocheredi_zheleznodorozhnogo_obhoda_Ukrainy.svg_-179x300.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16902 alignright\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/800px-Shema_I_ocheredi_zheleznodorozhnogo_obhoda_Ukrainy.svg_-179x300.png\" alt=\"800px-Shema_I_ocheredi_zheleznodorozhnogo_obhoda_Ukrainy.svg_-179x300\" width=\"179\" height=\"300\" \/><\/a>\u201eDies ist ein strategisches Projekt, in k\u00fcrzester Zeit \u2013 bis Ende 2017 \u2013 steht uns der Bau einer 122 Kilometer langen, zweigleisigen elektrifizierten Eisenbahnlinie bevor\u201c, &#8211; <a href=\"http:\/\/tass.ru\/ekonomika\/2293376\">sagte<\/a> der Vizepr\u00e4sident von Russian Railways Oleg Toni am 26. September 2015. Damals wurden auch die ungef\u00e4hren Kosten f\u00fcr Errichtung der Linie bekanntgegeben: \u201eF\u00fcr 2015 haben wir 6,5 Mrd. Rubel f\u00fcr dieses Projekt eingeplant. Das Hauptaugenmerk liegt auf auf der Bauprojektierung, es darf keine Junk-Arbeit geben, da es um gro\u00dfe \u00f6ffentliche Gelder geht.\u201c<\/p>\n<p align=\"JUSTIFY\">Die wichtigste Aufgabe im Jahr 2015 war alles das auszuarbeiten, was 2016 eingeplant sein sollte, da dieser Plan \u201esehr viel ernster als der diesj\u00e4hrige ist \u2013 das sind fast 18 Mrd. Rubel\u201c. \u201eWir m\u00fcssen unter Ber\u00fccksichtigung dieses Jahres praktisch 60 Prozent der Arbeiten erledigen\u201c, &#8211; formulierte der Vizepr\u00e4sident von Russian Railways es genauer.<\/p>\n<p align=\"JUSTIFY\"><strong>Also m\u00fcssen bis Ende 2016 nur 60 Prozent der Arbeiten fertiggestellt sein und die Kostensumme \u00fcberschreitet schon 24,5 Mrd. Rubel. Und das alles wegen einem 37 Kilometer langen Abschnitt, der im Heute durch das Gebiet Luhansk verl\u00e4uft.<\/strong><\/p>\n<p align=\"JUSTIFY\">Sicherlich sprengen die Kosten der Eisenbahnlinie zur Umgehung der Ukraine die der Kertsch-Br\u00fccke (211,9 Mrd. Rubel) vorerst noch nicht, nichtsdestotrotz ist die Summe imposant und entspricht den Mitteln, die beispielsweise f\u00fcr die medizinische Versorgung zur Verf\u00fcgung gestellt werden. So sind f\u00fcr 2016 f\u00fcr dasselbe Woronesch-Gebiet 27,5 Mrd. Rubel f\u00fcr die Gesundheitsversorgung <a href=\"https:\/\/riavrn.ru\/news\/voronezhskaya-oblduma-utverdila-byudzhet-regiona-na-2016-god\/\">eingeplant<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Dieses Material wurde von <strong><a href=\"https:\/\/twitter.com\/krmvictory\">Victory Krm<\/a><\/strong> exklusiv f\u00fcr <a href=\"https:\/\/informnapalm.org\/22618-rossiya-zabila-pervyj-bolt\/\">InformNapalm<\/a> vorbereitet; \u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/kateryna.matey?fref=ts\">Kateryna Matey<\/a>. <strong>Beim Nachdruck und Verwenden des Materials ist ein Hinweis auf den Auto und unser Projekt erforderlich.<\/strong><\/em><\/p>\n<p><em><strong>CC BY 4.0<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 20. April 2016 besuchten hohe Milit\u00e4rbeamte den S\u00fcdlichen Milit\u00e4rbezirk der Russischen F\u00f6deration. Der erste russische stellvertretende&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[98,228,1],"tags":[9,312,826,156,783],"class_list":["post-16895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-informnapalm-eilmeldungen","category-beweise","tag-donbass","tag-eisenbahn","tag-eisenbahnlinie","tag-luhansk","tag-woronesch"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets - InformNapalm (Deutsch)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets - InformNapalm (Deutsch)\" \/>\n<meta property=\"og:description\" content=\"Am 20. April 2016 besuchten hohe Milit\u00e4rbeamte den S\u00fcdlichen Milit\u00e4rbezirk der Russischen F\u00f6deration. Der erste russische stellvertretende...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/\" \/>\n<meta property=\"og:site_name\" content=\"InformNapalm (Deutsch)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/informnapalm24\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/oxanatinko\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-30T08:38:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/bolt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"642\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/\"},\"author\":{\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#\\\/schema\\\/person\\\/96ae00c3b1d58255bc6559a1b070bf9a\"},\"headline\":\"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets\",\"datePublished\":\"2016-04-30T08:38:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/\"},\"wordCount\":601,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/bolt.jpg\",\"keywords\":[\"Donbass\",\"Eisenbahn\",\"Eisenbahnlinie\",\"Luhansk\",\"Woronesch\"],\"articleSection\":[\"Aktuell\",\"InformNapalm\",\"Photo und Videobeweise\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/\",\"url\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/\",\"name\":\"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets - InformNapalm (Deutsch)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/bolt.jpg\",\"datePublished\":\"2016-04-30T08:38:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#\\\/schema\\\/person\\\/96ae00c3b1d58255bc6559a1b070bf9a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#primaryimage\",\"url\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/bolt.jpg\",\"contentUrl\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/bolt.jpg\",\"width\":642,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/\",\"name\":\"InformNapalm (Deutsch)\",\"description\":\"OSINT, HUMINT, Analytik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#\\\/schema\\\/person\\\/96ae00c3b1d58255bc6559a1b070bf9a\",\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"caption\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\"},\"sameAs\":[\"https:\\\/\\\/informnapalm.org\\\/\",\"https:\\\/\\\/www.facebook.com\\\/oxanatinko\",\"https:\\\/\\\/x.com\\\/oxana_tinko\"],\"url\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/author\\\/oxana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets - InformNapalm (Deutsch)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/","og_locale":"de_DE","og_type":"article","og_title":"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets - InformNapalm (Deutsch)","og_description":"Am 20. April 2016 besuchten hohe Milit\u00e4rbeamte den S\u00fcdlichen Milit\u00e4rbezirk der Russischen F\u00f6deration. Der erste russische stellvertretende...","og_url":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/","og_site_name":"InformNapalm (Deutsch)","article_publisher":"https:\/\/www.facebook.com\/informnapalm24","article_author":"https:\/\/www.facebook.com\/oxanatinko","article_published_time":"2016-04-30T08:38:38+00:00","og_image":[{"width":642,"height":336,"url":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/bolt.jpg","type":"image\/jpeg"}],"author":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","twitter_misc":{"Verfasst von":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#article","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/"},"author":{"name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a"},"headline":"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets","datePublished":"2016-04-30T08:38:38+00:00","mainEntityOfPage":{"@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/"},"wordCount":601,"commentCount":0,"image":{"@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/bolt.jpg","keywords":["Donbass","Eisenbahn","Eisenbahnlinie","Luhansk","Woronesch"],"articleSection":["Aktuell","InformNapalm","Photo und Videobeweise"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/","url":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/","name":"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets - InformNapalm (Deutsch)","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#primaryimage"},"image":{"@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/bolt.jpg","datePublished":"2016-04-30T08:38:38+00:00","author":{"@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a"},"breadcrumb":{"@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#primaryimage","url":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/bolt.jpg","contentUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/bolt.jpg","width":642,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/informnapalm.org\/de\/russland-schlaegt-den-ersten-bolzen-in-die-eisenbahnlinie-zur-umgehung-des-luhansker-gebiets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/informnapalm.org\/de\/"},{"@type":"ListItem","position":2,"name":"Russland schl\u00e4gt den ersten Bolzen in die Eisenbahnlinie zur Umgehung des Luhansker Gebiets"}]},{"@type":"WebSite","@id":"https:\/\/informnapalm.org\/de\/#website","url":"https:\/\/informnapalm.org\/de\/","name":"InformNapalm (Deutsch)","description":"OSINT, HUMINT, Analytik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informnapalm.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a","name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","caption":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e"},"sameAs":["https:\/\/informnapalm.org\/","https:\/\/www.facebook.com\/oxanatinko","https:\/\/x.com\/oxana_tinko"],"url":"https:\/\/informnapalm.org\/de\/author\/oxana\/"}]}},"views":2970,"post_src":"Am 20. April 2016 besuchten hohe Milit\u00e4rbeamte den S\u00fcdlichen Milit\u00e4rbezirk der Russischen F\u00f6deration. Der erste russische stellvertretende Verteidigungsminister, Armeegeneral Ruslan Zalikow und der stellvertretende russische Verteidigungsminister, Armeegeneral Dmitri Bulgakow reisten zur Inspektion in die Gebiete Woronesch und Rostow. Das Ziel des Besuchs war die Durchf\u00fchrung der Kontrolle des Bauablaufs der zweigleisigen elektrischen Eisenbahnlinie, deren Baubeginn vor einem Jahr am 25. April 2015 zur Umgehung der Ukraine im Bereich Zhurawka \u2013 Millerowo war.\r\n<p align=\"JUSTIFY\"><a href=\"http:\/\/wikimapia.org\/#lang=en&amp;lat=49.774613&amp;lon=39.806213&amp;z=11&amp;m=b&amp;show=\/32870873\/ru\/\u041f\u0435\u0440\u0432\u044b\u0439-\u0441\u0442\u0440\u043e\u044f\u0449\u0438\u0439\u0441\u044f-\u0443\u0447\u0430\u0441\u0442\u043e\u043a-\u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0439-\u0434\u043e\u0440\u043e\u0433\u0438-\u0432-\u043e\u0431\u0445\u043e\u0434-\u0423\u043a\u0440\u0430\u0438\u043d\u044b\">F\u00fcr die erste und zweite Bauetappe<\/a> waren die Erdaufbereitung und der Eisenbahnuntergrundbau auf einem Abschnitt von 11 bis 52,4 Kilometer vorgesehen. Diese Arbeiten wurden 2015 abgeschlossen.<\/p>\r\n<p align=\"JUSTIFY\">Einen Teilabschnitt des Eisenbahnuntergrundes ab der Station Zhurawka bis zur Station Nowopavlowka kann man <a href=\"https:\/\/browse.digitalglobe.com\/imagefinder\/showBrowseMetadata?csrfToken=mJ0H7dGhlpIRARl6dRY9bg36OIsTcFY%2Fegse50fmdU5lYJ0Hd6GvAifVpfzEHK5Gc%2BOj%2Bi32z%2BVy4eFC7ODuhB%2B6K5J4KM3AlEObDwLAFPbK%2FtkT77BIpWljSGZdZLxzNJHGOc9tCIFk%2B9wtsQzNoVtjKPVLnWmaraZuEuIzRAzaPs6849C98B5t8OFusDY54a3J2z87s4zGsVf0dTUiXycb%2FGHVc50PY1FQcdhhvkuJq83T1BVVkNCQWijLIyOO9kh4fN2ZsF7XyUDVECnxoDY68w%2BJ1ODavToEw%2BodqPHLJahHRIqWnnoeRO2ptjDwZZ%2BBhKEs0Jxfkh0JteTNKA%3D%3D&amp;buffer=1.0&amp;catalogId=10400100174B4900&amp;imageHeight=natres&amp;imageWidth=natres\">auf dem Satellitenbild vom 11. Januar 2016<\/a> von DigitalGlobe erkennen. Leider wurden auf anderen Karten die Satellitenaufnahmen dieses Gebietes bislang noch nicht aktualisiert und wir k\u00f6nnen uns nicht vergewissern, bis zum welchen Punkt der Bahndamm tats\u00e4chlich errichtet wurde.<\/p>\r\n<p align=\"JUSTIFY\"><a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3.jpg\"><img class=\"aligncenter size-full wp-image-16900\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-3.jpg\" alt=\"Kantemirovka-3\" width=\"1348\" height=\"643\" \/><\/a><\/p>\r\nF\u00fcr die Durchf\u00fchrung der geplanten Arbeiten werden Soldaten der Eisenbahntruppen herangezogen, die in regelm\u00e4\u00dfigen Abst\u00e4nden durch den Dreck waten und die Technik aus dem Sumpf holen. Die Arbeiten werden auch in der Winterzeit verrichtet. In den Sozialnetzwerkprofilen der Soldaten gelang es einige Aufnahmen von der Baustelle ausfindig zu machen.\r\n\r\n<a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1.jpg\"><img class=\"aligncenter size-full wp-image-16901\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Technik-1.jpg\" alt=\"Technik-1\" width=\"2560\" height=\"1920\" \/><\/a>\r\n<p align=\"JUSTIFY\"><a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-2.jpg\"><img class=\" wp-image-16899 alignnone\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka-2.jpg\" alt=\"Kantemirovka-2\" width=\"280\" height=\"251\" \/><\/a> <a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka.jpg\"><img class=\" wp-image-16898 alignnone\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/Kantemirovka.jpg\" alt=\"Kantemirovka\" width=\"267\" height=\"254\" \/><\/a><\/p>\r\n<p align=\"JUSTIFY\">Laut den Medien haben die Gener\u00e4le Zalikow und Bulgakow w\u00e4hrend ihres Besuch den Startschuss f\u00fcr die Verlegung des Gleisrostes <a href=\"http:\/\/www.vesti.ru\/doc.html?id=2745229\">gegeben<\/a>, indem sie m<strong>it Schraubenschl\u00fcsseln die Bolzen auf die Verbindungsstellen zweier Gleisverbindungen im Bereich Zhurawka \u2013 Millerowo gedreht haben<\/strong>. Die weitere Verlegung des Gleisrostes werden Spezialisten-Streckenbauer der Eisenbahntruppen der offenen Aktiengesellschaft Russian Railways durchf\u00fchren.<\/p>\r\n<p align=\"JUSTIFY\">In sowjetischer Tradition wird die Fertigstellung jeder Bauetappe bei den Soldaten mit Meldungen von der Unterbietung der Baufristen begleitet. Seit Baubeginn ist genau ein Jahr vergangen, vollst\u00e4ndig sind jedoch lediglich zwei Etappen abgeschlossen. Zum jetzigen Zeitpunkt sind die Eisenbahntruppen nur bis an die Grenzen des russischen Gebietes Rostow vorangekommen und weiter stehen der schwierige Bau einer Br\u00fccke \u00fcber den Fluss Kalitwa und der nicht k\u00fcrzerer Abschnitt bis nach Millerowo auf dem Plan.<\/p>\r\n<p align=\"JUSTIFY\"><a href=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/800px-Shema_I_ocheredi_zheleznodorozhnogo_obhoda_Ukrainy.svg_-179x300.png\"><img class=\"size-full wp-image-16902 alignright\" src=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2016\/04\/800px-Shema_I_ocheredi_zheleznodorozhnogo_obhoda_Ukrainy.svg_-179x300.png\" alt=\"800px-Shema_I_ocheredi_zheleznodorozhnogo_obhoda_Ukrainy.svg_-179x300\" width=\"179\" height=\"300\" \/><\/a>\u201eDies ist ein strategisches Projekt, in k\u00fcrzester Zeit \u2013 bis Ende 2017 \u2013 steht uns der Bau einer 122 Kilometer langen, zweigleisigen elektrifizierten Eisenbahnlinie bevor\u201c, - <a href=\"http:\/\/tass.ru\/ekonomika\/2293376\">sagte<\/a> der Vizepr\u00e4sident von Russian Railways Oleg Toni am 26. September 2015. Damals wurden auch die ungef\u00e4hren Kosten f\u00fcr Errichtung der Linie bekanntgegeben: \u201eF\u00fcr 2015 haben wir 6,5 Mrd. Rubel f\u00fcr dieses Projekt eingeplant. Das Hauptaugenmerk liegt auf auf der Bauprojektierung, es darf keine Junk-Arbeit geben, da es um gro\u00dfe \u00f6ffentliche Gelder geht.\u201c<\/p>\r\n<p align=\"JUSTIFY\">Die wichtigste Aufgabe im Jahr 2015 war alles das auszuarbeiten, was 2016 eingeplant sein sollte, da dieser Plan \u201esehr viel ernster als der diesj\u00e4hrige ist \u2013 das sind fast 18 Mrd. Rubel\u201c. \u201eWir m\u00fcssen unter Ber\u00fccksichtigung dieses Jahres praktisch 60 Prozent der Arbeiten erledigen\u201c, - formulierte der Vizepr\u00e4sident von Russian Railways es genauer.<\/p>\r\n<p align=\"JUSTIFY\"><strong>Also m\u00fcssen bis Ende 2016 nur 60 Prozent der Arbeiten fertiggestellt sein und die Kostensumme \u00fcberschreitet schon 24,5 Mrd. Rubel. Und das alles wegen einem 37 Kilometer langen Abschnitt, der im Heute durch das Gebiet Luhansk verl\u00e4uft.<\/strong><\/p>\r\n<p align=\"JUSTIFY\">Sicherlich sprengen die Kosten der Eisenbahnlinie zur Umgehung der Ukraine die der Kertsch-Br\u00fccke (211,9 Mrd. Rubel) vorerst noch nicht, nichtsdestotrotz ist die Summe imposant und entspricht den Mitteln, die beispielsweise f\u00fcr die medizinische Versorgung zur Verf\u00fcgung gestellt werden. So sind f\u00fcr 2016 f\u00fcr dasselbe Woronesch-Gebiet 27,5 Mrd. Rubel f\u00fcr die Gesundheitsversorgung <a href=\"https:\/\/riavrn.ru\/news\/voronezhskaya-oblduma-utverdila-byudzhet-regiona-na-2016-god\/\">eingeplant<\/a>.<\/p>\r\n&nbsp;\r\n\r\n<em>Dieses Material wurde von <strong><a href=\"https:\/\/twitter.com\/krmvictory\">Victory Krm<\/a><\/strong> exklusiv f\u00fcr <a href=\"https:\/\/informnapalm.org\/22618-rossiya-zabila-pervyj-bolt\/\">InformNapalm<\/a> vorbereitet; \u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/kateryna.matey?fref=ts\">Kateryna Matey<\/a>. <strong>Beim Nachdruck und Verwenden des Materials ist ein Hinweis auf den Auto und unser Projekt erforderlich.<\/strong><\/em>\r\n\r\n<em><strong>CC BY 4.0<\/strong><\/em>","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/16895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/comments?post=16895"}],"version-history":[{"count":1,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/16895\/revisions"}],"predecessor-version":[{"id":16903,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/16895\/revisions\/16903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/media\/16897"}],"wp:attachment":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/media?parent=16895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/categories?post=16895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/tags?post=16895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}