{"id":2252,"date":"2015-01-07T19:13:05","date_gmt":"2015-01-07T19:13:05","guid":{"rendered":"https:\/\/informnapalm.org\/de\/?p=2252"},"modified":"2016-02-06T00:07:01","modified_gmt":"2016-02-06T00:07:01","slug":"die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla","status":"publish","type":"post","link":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/","title":{"rendered":"Die Chronik eines &#8222;Waffenstillstandes&#8220;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla"},"content":{"rendered":"<p>Anfang des Jahres 2015 tauchten im Internet einige Videos auf, auf denen russische Milit\u00e4rangeh\u00f6rige vor der Kamera posieren und zur Schau die ukrainischen Stellungen beschie\u00dfen, dabei verstecken sie sich zwischen den H\u00e4usern der Zivilsten am Rande des Dorfes Styla (Starobeschewski Bezirk im Gebiet Donezk, Ukraine).<br \/>\nDen Ort der Aufnahmen genau zu identifizieren hat uns ein Freund des Teams InformNapalm, der bekannte europ\u00e4ische Blogger und Analytiker Dajey Petros, geholfen.<\/p>\n<p>In seinem Blog <a href=\"http:\/\/ukraineatwar.blogspot.co.uk\/2015\/01\/russian-armor-attacking-ukrainian.html\">Ukraine@war<\/a> hat er die Gegend einwandfrei identifiziert.<\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4439\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg\" alt=\"Styla 1\" width=\"944\" height=\"638\" \/><\/a> <a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4440\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-4-1024x702.jpg\" alt=\"Styla 4\" width=\"1024\" height=\"702\" \/><\/a> <a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4442\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-8.jpg\" alt=\"Styla 8\" width=\"944\" height=\"638\" \/><\/a><\/p>\n<p>Au\u00dferdem hat er die Richtung aufgezeigt, aus der die ukrainischen Stellungen beschossen wurden.<\/p>\n<p><a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4441\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-5-1024x702.jpg\" alt=\"Styla 5\" width=\"1024\" height=\"702\" \/><\/a><\/p>\n<p>Jetzt m\u00f6chten wir auf die Aufnahmen selbst zur\u00fcckkommen, die wahrscheinlich Ende Dezember 2014 entstanden sind.<br \/>\nInteressant sind dabei der Ablauf und die Reihenfolge.<\/p>\n<p>Auf dem ersten Video sehen wir russische Soldaten, die &#8222;Damen&#8220; aus den Reihen der Rebellen auf einem BTR-80 spazieren fahren und dabei die Szenen aus dem Film &#8222;Titanik&#8220; nachahmen.<\/p>\n<p>Auf dem zweiten Video posieren die russischen Terroristen schon im Dorf Styla, einige tragen Abzeichen mit der &#8222;Fledermaus&#8220; &#8211; ein Symbol der russischen Aufkl\u00e4rungseinheiten, wenn auch in letzter Zeit dieses Symbol jeder, dem danach ist, sich an die Uniform klatscht &#8211; vom Speznas GRU bis zu den Randgruppen der Rebellen aus der Einheit &#8222;Batman&#8220;.<\/p>\n<p>Einige der neugebackenen &#8222;Speznas&#8220; tragen die russische Felduniform, und andere die veraltete ukrainische Felduniform. Das f\u00fchrt uns zur Vermutung, dass die russischen Soldaten Provokationen vorbereiten, m\u00f6glicherweise gegen die Zivilbev\u00f6lkerung.<\/p>\n<p>Laut dem Kommentar im Hintergrund wurden die Angeh\u00f6rigen dieser Einheit schon mal in der Ukraine &#8222;erwischt&#8220;. &#8222;Mich haben die, verf***, auch schon auf ihrer Website reingestellt, und ich wollte doch noch nach Paris&#8220;, &#8211; res\u00fcmiert der &#8222;Kameramann&#8220;, was wahrscheinlich bedeuten soll, dass seine pers\u00f6nlichen Daten auf den Seiten &#8222;<a href=\"http:\/\/lostivan.com\/\">LostIvan<\/a>&#8220; oder &#8222;<a href=\"https:\/\/psb4ukr.org\/\">Mirotworez<\/a>&#8220; (=&#8220;Friedensstifter&#8220;) ver\u00f6ffentlicht wurden.<\/p>\n<p>Au\u00dferdem sehen wir, wie die Soldaten schwere Milit\u00e4rfahrzeuge &#8211; Panzer T-64, BTR-80 und BMP-2 (taktische Nummer &#8222;254&#8220;) zwischen den bewohnten H\u00e4usern im Dorf aufstellen. Die Taktik der &#8222;menschlichen Schutzschilder&#8220; wird von den russischen Milit\u00e4rs oft eingesetzt und wurde bei vielen bewaffneten Konflikten erprobt.<\/p>\n<p>Das dritte Video zeigt uns die gleiche Technik der Raschisten am gleichen Ort, aber aus anderen Blickwinkeln. Hier taucht auch die taktische Nummer des BMP im Bild auf, was uns erm\u00f6glicht, die Maschine der russischen Armee zuzuordnen.<\/p>\n<p>Das vierte und letzte Video dieser Reihe zeigt uns, wie die russischen Truppen die ukrainischen Stellungen beschie\u00dfen. Auffallend ist, dass die Raschisten sich zwischen den H\u00e4usern der Bewohner von Styla vor dem Gegenangriff verstecken.<\/p>\n<p>Also zeigen uns alle 4 Videos deutlich, wer und wie gegen die ukrainischen Kr\u00e4fte w\u00e4hrend des sogenannten &#8222;Waffenstillstandes&#8220; k\u00e4mpft. Die Dreistigkeit der russischen Seite hat keine Grenzen, russische Soldaten und S\u00f6ldner offenbaren praktisch ihre Pr\u00e4senz in Donbass, zeigen, wie sie auf ukrainische Truppen schie\u00dfen und die Zivilisten terrorisieren, wobei die Zivilisten den Angriffen ausgesetzt und als &#8222;menschliche Schutzschilder&#8220; missbraucht werden. Hier sind nicht die Sanktionen n\u00f6tig, sondern eine harte und angemessene Antwort vonseiten nicht nur der Ukraine, sondern der ganzen Weltgemeinschaft.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Dieses Material wurde von <a href=\"https:\/\/www.facebook.com\/burkonews?fref=ts\">Roman Burko<\/a> und <strong>Al Gri<\/strong>\u00a0exklusiv f\u00fcr\u00a0<a href=\"https:\/\/informnapalm.org\/4438-hronyka-peremyryya-vs-rf-yz-zhylogo-massyva-v-style-vedet-obstrely-ukraynskyh-pozytsyj\/\">InformNapalm<\/a> vorbereitet;\u00a0\u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/olena.kopnick?fref=ts\">Olena K\u00f6pnick<\/a>. Ein Dank an <a href=\"https:\/\/twitter.com\/DajeyPetros\/status\/552494330125250560\">Dajey Petros<\/a> f\u00fcr freundliche Hilfe. Beim Nachdruck und Verwenden des Materials ist ein Hinweis auf unsere Ressource erforderlich.\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anfang des Jahres 2015 tauchten im Internet einige Videos auf, auf denen russische Milit\u00e4rangeh\u00f6rige vor der Kamera&#8230;<\/p>\n","protected":false},"author":1,"featured_media":-1,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[98,1],"tags":[66,87,59,710],"class_list":["post-2252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-beweise","tag-donezk","tag-invasion","tag-krieg","tag-styla"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Chronik eines &quot;Waffenstillstandes&quot;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla - InformNapalm (Deutsch)<\/title>\n<meta name=\"description\" content=\"Die Chronik eines &quot;Waffenstillstandes&quot;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Chronik eines &quot;Waffenstillstandes&quot;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla - InformNapalm (Deutsch)\" \/>\n<meta property=\"og:description\" content=\"Die Chronik eines &quot;Waffenstillstandes&quot;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/\" \/>\n<meta property=\"og:site_name\" content=\"InformNapalm (Deutsch)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/informnapalm24\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/oxanatinko\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-07T19:13:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-06T00:07:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/02\/wir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/\"},\"author\":{\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#\\\/schema\\\/person\\\/96ae00c3b1d58255bc6559a1b070bf9a\"},\"headline\":\"Die Chronik eines &#8222;Waffenstillstandes&#8220;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla\",\"datePublished\":\"2015-01-07T19:13:05+00:00\",\"dateModified\":\"2016-02-06T00:07:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/\"},\"wordCount\":562,\"image\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/informnapalm.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/Styla-1.jpg\",\"keywords\":[\"Donezk\",\"Invasion\",\"Krieg\",\"Styla\"],\"articleSection\":[\"Aktuell\",\"Photo und Videobeweise\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/\",\"url\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/\",\"name\":\"Die Chronik eines \\\"Waffenstillstandes\\\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla - InformNapalm (Deutsch)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/informnapalm.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/Styla-1.jpg\",\"datePublished\":\"2015-01-07T19:13:05+00:00\",\"dateModified\":\"2016-02-06T00:07:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#\\\/schema\\\/person\\\/96ae00c3b1d58255bc6559a1b070bf9a\"},\"description\":\"Die Chronik eines \\\"Waffenstillstandes\\\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/informnapalm.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/Styla-1.jpg\",\"contentUrl\":\"https:\\\/\\\/informnapalm.org\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/Styla-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Chronik eines &#8222;Waffenstillstandes&#8220;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/\",\"name\":\"InformNapalm (Deutsch)\",\"description\":\"OSINT, HUMINT, Analytik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/#\\\/schema\\\/person\\\/96ae00c3b1d58255bc6559a1b070bf9a\",\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"caption\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\"},\"sameAs\":[\"https:\\\/\\\/informnapalm.org\\\/\",\"https:\\\/\\\/www.facebook.com\\\/oxanatinko\",\"https:\\\/\\\/x.com\\\/oxana_tinko\"],\"url\":\"https:\\\/\\\/informnapalm.org\\\/de\\\/author\\\/oxana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Chronik eines \"Waffenstillstandes\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla - InformNapalm (Deutsch)","description":"Die Chronik eines \"Waffenstillstandes\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/","og_locale":"de_DE","og_type":"article","og_title":"Die Chronik eines \"Waffenstillstandes\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla - InformNapalm (Deutsch)","og_description":"Die Chronik eines \"Waffenstillstandes\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla","og_url":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/","og_site_name":"InformNapalm (Deutsch)","article_publisher":"https:\/\/www.facebook.com\/informnapalm24","article_author":"https:\/\/www.facebook.com\/oxanatinko","article_published_time":"2015-01-07T19:13:05+00:00","article_modified_time":"2016-02-06T00:07:01+00:00","og_image":[{"width":1000,"height":650,"url":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/02\/wir.jpg","type":"image\/jpeg"}],"author":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","twitter_misc":{"Verfasst von":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/#article","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/"},"author":{"name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a"},"headline":"Die Chronik eines &#8222;Waffenstillstandes&#8220;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla","datePublished":"2015-01-07T19:13:05+00:00","dateModified":"2016-02-06T00:07:01+00:00","mainEntityOfPage":{"@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/"},"wordCount":562,"image":{"@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg","keywords":["Donezk","Invasion","Krieg","Styla"],"articleSection":["Aktuell","Photo und Videobeweise"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/","url":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/","name":"Die Chronik eines \"Waffenstillstandes\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla - InformNapalm (Deutsch)","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/#primaryimage"},"image":{"@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg","datePublished":"2015-01-07T19:13:05+00:00","dateModified":"2016-02-06T00:07:01+00:00","author":{"@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a"},"description":"Die Chronik eines \"Waffenstillstandes\": russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla","breadcrumb":{"@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/#primaryimage","url":"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg","contentUrl":"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/informnapalm.org\/de\/die-chronik-eines-waffenstillstandes-russische-streitkraefte-beschiessen-ukrainische-stellungen-aus-einem-wohngebiet-im-dorf-styla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/informnapalm.org\/de\/"},{"@type":"ListItem","position":2,"name":"Die Chronik eines &#8222;Waffenstillstandes&#8220;: russische Streitkr\u00e4fte beschie\u00dfen ukrainische Stellungen aus einem Wohngebiet im Dorf Styla"}]},{"@type":"WebSite","@id":"https:\/\/informnapalm.org\/de\/#website","url":"https:\/\/informnapalm.org\/de\/","name":"InformNapalm (Deutsch)","description":"OSINT, HUMINT, Analytik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informnapalm.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a","name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","caption":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e"},"sameAs":["https:\/\/informnapalm.org\/","https:\/\/www.facebook.com\/oxanatinko","https:\/\/x.com\/oxana_tinko"],"url":"https:\/\/informnapalm.org\/de\/author\/oxana\/"}]}},"views":2633,"post_src":"Anfang des Jahres 2015 tauchten im Internet einige Videos auf, auf denen russische Milit\u00e4rangeh\u00f6rige vor der Kamera posieren und zur Schau die ukrainischen Stellungen beschie\u00dfen, dabei verstecken sie sich zwischen den H\u00e4usern der Zivilsten am Rande des Dorfes Styla (Starobeschewski Bezirk im Gebiet Donezk, Ukraine).\r\nDen Ort der Aufnahmen genau zu identifizieren hat uns ein Freund des Teams InformNapalm, der bekannte europ\u00e4ische Blogger und Analytiker Dajey Petros, geholfen.\r\n\r\nIn seinem Blog <a href=\"http:\/\/ukraineatwar.blogspot.co.uk\/2015\/01\/russian-armor-attacking-ukrainian.html\">Ukraine@war<\/a> hat er die Gegend einwandfrei identifiziert.\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg\"><img class=\"aligncenter size-full wp-image-4439\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-1.jpg\" alt=\"Styla 1\" width=\"944\" height=\"638\" \/><\/a> <a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-4.jpg\"><img class=\"aligncenter size-large wp-image-4440\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-4-1024x702.jpg\" alt=\"Styla 4\" width=\"1024\" height=\"702\" \/><\/a> <a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-8.jpg\"><img class=\"aligncenter size-large wp-image-4442\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-8.jpg\" alt=\"Styla 8\" width=\"944\" height=\"638\" \/><\/a>\r\n\r\nAu\u00dferdem hat er die Richtung aufgezeigt, aus der die ukrainischen Stellungen beschossen wurden.\r\n\r\n<a href=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-5.jpg\"><img class=\"aligncenter size-large wp-image-4441\" src=\"https:\/\/informnapalm.org\/wp-content\/uploads\/2015\/01\/Styla-5-1024x702.jpg\" alt=\"Styla 5\" width=\"1024\" height=\"702\" \/><\/a>\r\n\r\nJetzt m\u00f6chten wir auf die Aufnahmen selbst zur\u00fcckkommen, die wahrscheinlich Ende Dezember 2014 entstanden sind.\r\nInteressant sind dabei der Ablauf und die Reihenfolge.\r\n\r\nAuf dem ersten Video sehen wir russische Soldaten, die \"Damen\" aus den Reihen der Rebellen auf einem BTR-80 spazieren fahren und dabei die Szenen aus dem Film \"Titanik\" nachahmen.\r\n\r\nAuf dem zweiten Video posieren die russischen Terroristen schon im Dorf Styla, einige tragen Abzeichen mit der \"Fledermaus\" - ein Symbol der russischen Aufkl\u00e4rungseinheiten, wenn auch in letzter Zeit dieses Symbol jeder, dem danach ist, sich an die Uniform klatscht - vom Speznas GRU bis zu den Randgruppen der Rebellen aus der Einheit \"Batman\".\r\n\r\nEinige der neugebackenen \"Speznas\" tragen die russische Felduniform, und andere die veraltete ukrainische Felduniform. Das f\u00fchrt uns zur Vermutung, dass die russischen Soldaten Provokationen vorbereiten, m\u00f6glicherweise gegen die Zivilbev\u00f6lkerung.\r\n\r\nLaut dem Kommentar im Hintergrund wurden die Angeh\u00f6rigen dieser Einheit schon mal in der Ukraine \"erwischt\". \"Mich haben die, verf***, auch schon auf ihrer Website reingestellt, und ich wollte doch noch nach Paris\", - res\u00fcmiert der \"Kameramann\", was wahrscheinlich bedeuten soll, dass seine pers\u00f6nlichen Daten auf den Seiten \"<a href=\"http:\/\/lostivan.com\/\">LostIvan<\/a>\" oder \"<a href=\"https:\/\/psb4ukr.org\/\">Mirotworez<\/a>\" (=\"Friedensstifter\") ver\u00f6ffentlicht wurden.\r\n\r\nAu\u00dferdem sehen wir, wie die Soldaten schwere Milit\u00e4rfahrzeuge - Panzer T-64, BTR-80 und BMP-2 (taktische Nummer \"254\") zwischen den bewohnten H\u00e4usern im Dorf aufstellen. Die Taktik der \"menschlichen Schutzschilder\" wird von den russischen Milit\u00e4rs oft eingesetzt und wurde bei vielen bewaffneten Konflikten erprobt.\r\n\r\nDas dritte Video zeigt uns die gleiche Technik der Raschisten am gleichen Ort, aber aus anderen Blickwinkeln. Hier taucht auch die taktische Nummer des BMP im Bild auf, was uns erm\u00f6glicht, die Maschine der russischen Armee zuzuordnen.\r\n\r\nDas vierte und letzte Video dieser Reihe zeigt uns, wie die russischen Truppen die ukrainischen Stellungen beschie\u00dfen. Auffallend ist, dass die Raschisten sich zwischen den H\u00e4usern der Bewohner von Styla vor dem Gegenangriff verstecken.\r\n\r\nAlso zeigen uns alle 4 Videos deutlich, wer und wie gegen die ukrainischen Kr\u00e4fte w\u00e4hrend des sogenannten \"Waffenstillstandes\" k\u00e4mpft. Die Dreistigkeit der russischen Seite hat keine Grenzen, russische Soldaten und S\u00f6ldner offenbaren praktisch ihre Pr\u00e4senz in Donbass, zeigen, wie sie auf ukrainische Truppen schie\u00dfen und die Zivilisten terrorisieren, wobei die Zivilisten den Angriffen ausgesetzt und als \"menschliche Schutzschilder\" missbraucht werden. Hier sind nicht die Sanktionen n\u00f6tig, sondern eine harte und angemessene Antwort vonseiten nicht nur der Ukraine, sondern der ganzen Weltgemeinschaft.\r\n\r\n&nbsp;\r\n\r\n<em>Dieses Material wurde von <a href=\"https:\/\/www.facebook.com\/burkonews?fref=ts\">Roman Burko<\/a> und <strong>Al Gri<\/strong>\u00a0exklusiv f\u00fcr\u00a0<a href=\"https:\/\/informnapalm.org\/4438-hronyka-peremyryya-vs-rf-yz-zhylogo-massyva-v-style-vedet-obstrely-ukraynskyh-pozytsyj\/\">InformNapalm<\/a> vorbereitet;\u00a0\u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/olena.kopnick?fref=ts\">Olena K\u00f6pnick<\/a>. Ein Dank an <a href=\"https:\/\/twitter.com\/DajeyPetros\/status\/552494330125250560\">Dajey Petros<\/a> f\u00fcr freundliche Hilfe. Beim Nachdruck und Verwenden des Materials ist ein Hinweis auf unsere Ressource erforderlich.\u00a0<\/em>\r\n\r\n&nbsp;","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/2252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/comments?post=2252"}],"version-history":[{"count":7,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/2252\/revisions"}],"predecessor-version":[{"id":14743,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/2252\/revisions\/14743"}],"wp:attachment":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/media?parent=2252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/categories?post=2252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/tags?post=2252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}