{"id":3933,"date":"2015-03-01T20:05:59","date_gmt":"2015-03-01T20:05:59","guid":{"rendered":"https:\/\/informnapalm.org\/de\/?p=3933"},"modified":"2017-10-09T11:27:47","modified_gmt":"2017-10-09T11:27:47","slug":"information-frankenstein-oder-reale-folgen-des-informationskrieges","status":"publish","type":"post","link":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/","title":{"rendered":"Information-Frankenstein oder reale Folgen des Informationskrieges"},"content":{"rendered":"<p style=\"text-align: right\" align=\"RIGHT\"><i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\">Wei\u00dft Du denn, worin wir stark sind, Basmanow?<\/i><\/p>\n<p style=\"text-align: right\" align=\"RIGHT\"><i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\">Nicht mit dem Heer, nein, nicht mit der Hilfe Polens,<\/i><\/p>\n<p style=\"text-align: right\" align=\"RIGHT\"><i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\">sondern mit der Meinung! Ja! Mit der Meinung unseres Volkes.<\/i><\/p>\n<p style=\"text-align: right\" align=\"RIGHT\">A.Puschkin \u201eBoris Godunow\u201c<\/p>\n<p>\u00dcber den Informationskrieg spricht derzeit vielleicht nur ein Faulpelz nicht (wobei vieles, was im Medienraum passiert, richtiger als \u201eInformationsterrorismus\u201c zu bezeichnen w\u00e4re, wie es <a href=\"https:\/\/informnapalm.org\/de\/w-pastuchow-zu-spaet-zu-schreien-boris-nemzow-wurde-ermordet\/\">Boris Nemzow<\/a> formuliert hat). Russland agiert in diesem Krieg sehr raffiniert, indem es seine Taktik permanent \u00e4ndert, auf die Situation operativ reagiert und immer neuere Kr\u00e4fte in den Kampf wirft. Alles wie im realen Krieg.<\/p>\n<p><a href=\"https:\/\/informnapalm.org\/de\/15-jahre-geheimkrieg-putins-gegen-die-ukraine\/\">Er wird gegen die Ukraine schon mehrere Jahre gef\u00fchrt<\/a>, wom\u00f6glich all die Jahre der Unabh\u00e4ngigkeit, und hat in letzter Zeit einen besonderen Zynismus erreicht.<\/p>\n<p>Wir verlieren weiterhin Stellung f\u00fcr Stellung und Widerstand gibt es nicht genug, oft gibt es gar keinen. Und das Wichtigste: bis jetzt hat noch immer keine \u201eInformations-ATO\u201c angefangen.<\/p>\n<p>Wir wehren uns durch einzelne Auftritte von Politikern, Publizisten, Journalisten, Diskussionen beim FB, Talkshows im Fernsehen. In letzter Zeit gibt es sogar Probleme mit Talkshows, es scheint ganz so, als ob die Meinungsfreiheit jemandem an der Macht\u00a0ganz und gar nicht gef\u00e4llt. Den Krieg gegen die Informationsmonster f\u00fchren nur freiwillige Aktivisten. Wenn man hier eine milit\u00e4rische Analogie zieht, handelt es sich umeine Abwehr durch einzelne K\u00e4mpfer mit Gewehren und Maschinenpistolen gegen eine milit\u00e4rische Armada mit Panzern, Luftwaffe und Raketen. Das Kr\u00e4fteverh\u00e4ltnis ist ziemlich ungleich. Und viele unsere \u201eB\u00fcrger\u201c (ich kann das nicht ohne Anf\u00fchrungszeichen schreiben) k\u00e4mpfen in diesem Krieg noch immer auf der Seite des Aggressors.<\/p>\n<p>Von allen \u201emateriellen\u201c Verlusten sind zum heutigen Tag zwei die wichtigsten: 1. Die\u00a0<a href=\"https:\/\/informnapalm.org\/de\/krimer-kantstein-ein-jahr-spaeter-einzelheiten-der-russischen-sonderoperation-zur-krim-annexion\/\">Okkupation der Krim<\/a>\u00a0und\u00a02. Der Krieg im Donbass, der sich in eine humanit\u00e4re Katastrophe f\u00fcr die ganze Region hin\u00fcberw\u00e4chst. Man sollte anerkennen, dass die Einnahme und Annexion der Krim ein grelles Beispiel des Sieges im Informationskrieg ist. Sie wird zweifellos in alle Lehrb\u00fccher zur <a href=\"https:\/\/informnapalm.org\/de\/die-psychologie-eines-manipulators-ist-die-psychologie-eines-moerders\/\">Psychologie der Propaganda<\/a>\u00a0eingehen. Aber genauso offensichtlich ist, dass die Krim zur\u00fcckzuholen\u00a0ohne Gegeninformationskampf sehr schwierig wird, wenn es denn \u00fcberhaupt m\u00f6glich ist.<\/p>\n<p>Wir haben nicht nur reale geografische Regionen verloren. Wir haben riesige Gebiete im Informationsraum verloren, die sich mit \u201eparallelen Antiwelten\u201c gef\u00fcllt haben, gegen welche wir keinerlei Ma\u00dfnahmen ergreifen. Diese Niederlagen sind prim\u00e4r, sie sind der Grund aller weiteren materiellen Verluste. Wenn wir nicht die \u201eInformationsterritorien\u201c zur\u00fcckgewinnen, die in den K\u00f6pfen von Millionen Menschen existieren, werden wir auch keine geografischen Territorien zur\u00fcckerobern k\u00f6nnen.<\/p>\n<h2 style=\"text-align: center\"><strong>Putin ist der moderne Frankenstein<\/strong><\/h2>\n<p>Einmal bin ich im Internet auf die folgende Formel gesto\u00dfen (leider kenne ich den Autor nicht): <strong>\u201eDie halbe Wahrheit + die halbe Wahrheit = L\u00fcge\u201c<\/strong>. Die Formel ist nicht nur sch\u00f6n, sie spiegelt das Wesen der Erschaffung einer \u201ehochqualitativen L\u00fcge\u201c genial wieder, die einwandfrei funktioniert und in den K\u00f6pfen der Menschen einen festen Platz im System ihrer \u00dcberzeugungen einnimmt. Sie ist bei weitem effektiver als klare Fakes in der Art von \u201egekreuzigten Jungs\u201c und \u201ehingerichteten Gimpeln\u201c. Die Kraft dieser L\u00fcge besteht darin, dass sie eben keine leere Erfindung ist, sondern aus einzelnen Thesen erschaffen wird, die an sich nicht gelogen sind. Sie sind leicht erkennbar und dienen als \u201eSchl\u00fcssel\u201c zur Anbindung dieser L\u00fcge an die Wahrheit. Das ist dasselbe wie die Tatsache, dass man aus \u201ewahrhaftigen\u201c St\u00fcckchen eines Mosaiks ein Bild zusammenlegen kann, das vom Sinn und Inhalt her seinen Einzelteilen diametral entgegengesetzt ist.<\/p>\n<p>Im bekannten Roman der englischen Schriftstellerin Mary Shelley \u201eFrankenstein oder der moderne Prometheus\u201c erschafft der Held Victor Frankenstein ein menschen\u00e4hnliches Monster von einer Riesengr\u00f6\u00dfe und Kraft, das sp\u00e4ter aufh\u00f6rt, sich unterzuordnen und sich an seinem Erschaffer f\u00fcr sein Aussehen r\u00e4cht.<\/p>\n<p>Es t\u00f6tet Familienmitglieder von Frankenstein und f\u00fchrt schlie\u00dflich zu seinem eigenen Tod. Interessant ist hier die Tatsache, dass das Monster aus Einzelteilen der realen menschlichen K\u00f6rpern zusammengesetzt wurde. Das ist eine Art \u201eWunder der Transplantation\u201c, aber nicht zur Lebensrettung eines Menschen durch den Austausch eines defekten Organs, sondern mit dem Ziel, ein anderes Objekt (Subjekt) mit g\u00e4nzlich neuen Eigenschaften zu erschaffen.<\/p>\n<p>Etwas \u00e4hnliches ist auch im Informationsraum passiert.<\/p>\n<p>Die propagandistische Maschine des Kremls produziert nicht einfach nur \u201einformativ-propagandistischen Geschosse\u201c, die die Psyche eines Menschen besch\u00e4digen. Sie hat eine komplette Parallelrealit\u00e4t erschaffen, in der wie in einem separaten Land Dutzende Millionen Menschen leben.<\/p>\n<p>Nichts daran w\u00e4re neu (denn Parallelrealit\u00e4ten hat man auch in der Vergangenheit erschaffen, \u00fcberdies auch lange vor der Erfindung des Fernsehens und Internets), wenn es hier nicht einen Umstand g\u00e4be: Diese neue Realit\u00e4t hat eine ungeheuerliche Kraft entfaltet und begann faktisch, ein selbstst\u00e4ndiges Leben zu f\u00fchren. Wie das Monster aufgeh\u00f6rt hat, sich Frankenstein unterzuordnen, so hat auch diese monstr\u00f6se Realit\u00e4t aufgeh\u00f6rt, sich ihrem Hauptarchitekten Putin unterzuordnen.<\/p>\n<p>In dieser Realit\u00e4t befinden sich Dutzende Millionen Russen, darin sind Hunderttausende Donbas-Einwohner versunken (in erster Linie auf den Territorien, die von den \u201eDVR-LVR\u201c kontrolliert werden). Der Unterschied zwischen ihnen besteht darin, dass die Erstgenannten ein\u00a0alternative Alltagsrealit\u00e4t\u00a0zu ihrer Verf\u00fcgung haben, bei den anderen aber der reale und der virtuelle Informationsraum zu einem Ganzen verschmolzen sind, und sie sich nun im Zentrum des surrealen \u201eTheater des Absurdes\u201c befinden. Wenn man hier eine milit\u00e4rische Metapher anwendet, haben sie sich im Wirkungsherd der informativen Massenvernichtungswaffen wiedergefunden und sind im Grunde Verwundete (informativ gequetscht).<\/p>\n<p>Die Tatsache, dass die Informationswaffe t\u00f6ten kann und das im buchst\u00e4blichen Sinne, ist objektiv bewiesen, mit einer mathematischen Genauigkeit. Die Geschichte des Genozids in Ruanda 1994, der nach verschiedenen Angaben das Leben von 500 000 bis zu 1 000 000 Menschen weggefegt hat, demonstriert sehr beispielhaft die Rolle der Radiostation \u201eRadio der tausend H\u00fcgel\u201c beim Entfachen von nationalem Hass und mit Aufrufen zur Vernichtung der ethnischen Minderheit. Dem Harvard-\u00d6konomisten David Janagisawa-Drott ist \u00a0derBeweis gelungen, dass in Gegenden, in denen diese Radiostation nicht empfangen werden konnte, die Anzahl der wegen Mordes Verurteilten um 62-69% geringer war, als dort, wo diese Sendungen empfangen wurden. Die Zahlen sind mehr als \u00fcberzeugend und beweisen die Verantwortlichkeit der Medien f\u00fcr den Tod von Hunderttausenden Menschen.<\/p>\n<p>Dar\u00fcber kann man im Artikel<a href=\"http:\/\/snob.ru\/selected\/entry\/81673\"> \u201eTausend Tote f\u00fcr Tausend Worte. Wie die Propaganda in Ruanda funktionierte\u201c<\/a> nachlesen. \u00dcbrigens wurden die Moderatoren dieser Radiostation zu jahrelangen Haftstrafen verurteilt. Und dabei ist das Fernsehen\u00a0im Dienst der Propaganda weitaus effektiver als das Radio. Dar\u00fcber sollte man ernsthaft nachdenken.<\/p>\n<p>Die Haupteigenschaft des Informationskrieges Russlands ist die Verwendung moderner Psychologietechnologien (solche wie zum Beispiel die neuro-linguistische Programmierung) und ein nie zuvor gesehenes Ausma\u00df der L\u00fcge.<\/p>\n<p>Man sollte daran denken, dass die Resultate der Ansteckung mit den \u201eToxinen\u201c der Desinformation f\u00fcr die menschliche Psyche sehr dauerhaft sind, und ihre Folgen sogar nach ihrer Neutralisation weiter existent bleiben. Wenn man dies ber\u00fccksichtigt, kann man als eine wichtige Folge des modernen Informationskrieges die Tatsache betrachten, dass die von ihm erschaffene Realit\u00e4t nicht mehr zur\u00fcckzutransformieren, umzulenken, ja nicht einmal zu lokalisieren ist, und noch weniger ist diese zu veredeln, \u201ewahrhaftiger zu machen\u201c, zu entsch\u00e4rfen. Und dabei \u00fcbersteigt die Toxizit\u00e4t der L\u00fcge ja alle m\u00f6glichen Grenzen und hat ein Niveau erreicht, das nur mit Massenvernichtungswaffen zu vergleichen ist, und nach manchen Bewertungen sogar diese l\u00e4ngst \u00fcbertroffen hat. Eben darum ist Putin nun zu einer Geisel der von ihm selbst erschaffenen Situation geworden und kann seinen Weg ganz einfach nicht mehr verlassen. \u2028Er kann keinen allumfassenden Krieg gegen die Ukraine beginnen (wegen Sanktionen, mangelnder Ressourcen, Krise und vieler weiterer objektiver und subjektiver Gr\u00fcnde). Aber er kann auch nicht mehr anhalten, denn das von ihm erschaffene informativ-propagandistische Monster treibt ihn zum n\u00e4chsten Amok, es lechzt nach neuem Blut und geht keinerlei Kompromisse ein. Sich ihm nicht unterzuordnen ist Selbstmord (und wom\u00f6glich nicht nur ein politischer) &#8211; das Monster wird sich an seinem Erschaffer auf die raffinierteste Art r\u00e4chen (und es geschieht bereits).\u00a0Sich unterzuordnen ist der Weg zur Insania, in der aus Verzweiflung die schrecklichsten Schritte unternommen werden k\u00f6nnten, bis hin zur Anwendung von Atomwaffen.<\/p>\n<h2 style=\"text-align: center\"><strong>Zwei Arten des historischen Traumas: Trauma des Opfers und Trauma des Aggressors<\/strong><\/h2>\n<p>In der modernen sozialen Psychologie von gro\u00dfen Gruppen wird aktiv eine Theorie des kollektiven oder historischen Traumas entwickelt.<\/p>\n<p>Wir gehen von der Annahme aus, dass au\u00dfer dem individuellen Bewussten und dem Unbewussten als Charakteristikum von gro\u00dfen Menschengruppen noch das kollektive Bewusste und Unbewusste existiert. Und mit ihm existieren auch solche Erscheinungen wie ein kollektives Trauma, kollektiver Stolz, kollektive Scham. In letzter Zeit widmet sich auch die Publizistik diesem Thema, schauen Sie doch bitte zum Beispiel die Artikel von Ilja Kukulin <a href=\"http:\/\/postnauka.ru\/faq\/26580?_utl_t=fb\">\u201eHistorisches Trauma als eine kulturelle Erscheinung\u201c<\/a> und Michail Jampolski <a href=\"http:\/\/www.colta.ru\/articles\/specials\/6088\">\u201eWie urteilt man \u00fcber Sieger?\u201c<\/a><\/p>\n<p>So wird die Massenpsychologie des modernen Russland, die der heutigen Politik zugrunde liegt, mit dem Trauma des Imperiumszerfalls erkl\u00e4rt, was mit Versuchen, dieses zu restaurieren, kompensiert wird (die Idee der \u201eRussischen Welt\u201c), das \u201eAufstehen von den Knien\u201c, die Ausbeutung des Konzepts der Weltverschw\u00f6rung etc.<\/p>\n<p>Meiner Meinung nach ist es falsch zu denken, dass dem kollektiven Trauma nur die Opfer unterlegen sind. Obwohl es diesem Thema viele Untersuchungen gewidmet sind, sind bei weitem nicht alle Aspekte verst\u00e4ndlich. So hat man sehr wenig analysiert, was denn mit der kollektiven Psychologie der Aggressoren geschieht, inwieweit diese Erfahrung f\u00fcr sie traumatisch wird. Das einzige Thema, das wohl gestreift wurde, ist Deutschland nach dem Zweiten Weltkrieg, aber das ist ein Schicksal vom Halbaggressor-Halbopfer, das eine Niederlage in diesem Krieg erlitt. Wahrscheinlich darf man das Problem nicht nur von einem einzigen Standpunkt aus untersuchen, denn die Rollen des \u201eAggressoren\u201c und des \u201eOpfers\u201c sind oft gegenseitig verflochten, sie k\u00f6nnen ihre Pl\u00e4tze tauschen, wie im dramatischen Dreieck von Karpman.<\/p>\n<p>Wenn man diese Prozesse am Beispiel Russlands betrachtet (genauer \u2013 der Sowjetunion), so werden wir viele Fakten der kollektiven Traumatisierung durch die eigene Aggressivit\u00e4t sehen, wo die Gesellschaft gleichzeitig als ein Opfer und ein Aggressor auftritt. In erster Linie ist Russland (genauer- die Sowjetunion) ein Staat, der im Laufe von 50 Jahren die Bl\u00fcte seiner Nation vernichtete und faktisch einen intellektuellen und moralischen Genozid beging.<\/p>\n<p>Angefangen mit dem \u201eRoten Terror\u201c der 1920er Jahre, dem B\u00fcrgerkrieg und der ersten Emigrationswelle (in welcher die Bl\u00fcte der Nation ausgereist war: Wissenschaftler, Philosophen). Sp\u00e4ter gab es noch blutigere Ereignisse (Exekutionen und Zwangsarbeit der 1930er), Krieg, im Feuer dessen beste Vertreter der Nation nicht allein durch Feindesh\u00e4nde gefallen sind. Sehr beispielhaft ist das Verh\u00e4ltnis zu jenen, die aus der Gefangenschaft ausgebrochen waren, die die deutschen Konzentrationslager \u00fcberlebt hatten. In derselben Zeit wurden auch die Deportationen und der Genozid an ganzen V\u00f6lkern begangen (Tschetschenen, Krimtataren, Wolga-Deutschen und anderen). Eine der schrecklichsten Seiten dieser Geschichte ist der Holodomor der 1930er, der k\u00fcnstlich, ohne objektive Gr\u00fcnde (wie zum Beispiel Missernten) erschaffen wurde. Au\u00dfer der physischen Vernichtung wurden viele Menschen aus dem Land vertrieben oder sie haben es selbst verlassen, um sich vor Repressionen zu retten oder vor unmenschlichen Existenzbedingungen zu fl\u00fcchten.<\/p>\n<h2 style=\"text-align: center\"><strong>Historische Gr\u00fcnde<\/strong><\/h2>\n<p>H\u00f6chstwahrscheinlich hat das alles nicht erst 1917 angefangen, sondern besitzt tiefer gehende historische Wurzeln. Die Geschichte Russlands ist zumindest in den letzten 500 Jahren durch eine expansive Au\u00dfenpolitik gekennzeichnet (eine w\u00fcrdige Weiterf\u00fchrung von\u00a0Traditionen der Goldenen Horde). Faktisch stellt die ganze russische Geschichte die Eroberung von immer neueren Territorien dar, die dem unermesslichen Imperiums miangeschlossen wurden.<\/p>\n<p>Allein in den letzten 200\u00a0Jahren geschahen die Annexion der rechtsufrigen Ukraine, des Territoriums des Krimer Khanats, Georgiens (Ende 18.- Anfang 19. Jahrhunderts) , sp\u00e4ter gab es noch den Kaukasus-Krieg und die Unterjochung der V\u00f6lker des Nordkaukasus.<\/p>\n<p>Die zweite Komponente ist das Verh\u00e4ltnis des Staates zu seinem eigenen Volk, das sich traditionell auf der Ebene von Sklaven befand (die Leibeigenschaft existierte bei uns bis 1861 und wurde w\u00e4hrend der sowjetischen \u00c4ra faktisch wiederhergestellt). Dasselbe Verh\u00e4ltnis hatte man auch zu russischen Genies &#8211; man braucht sich nur an das tragische Schicksal von Puschkin, Lermontow, Gribojedow und vielen anderen zu erinnern. Nicht weniger tragisch verlief auch das Schicksal der Wissenschaftler und Erfinder, das wunderbar in der Gestalt von Lewscha in der Novelle von Leskow wiedergespiegelt wird. Lomonossow war wahrscheinlich eine gl\u00fcckliche Ausnahme, indem er faktisch in eine Ikone verwandelt wurde. Das Schicksal der Dekabristen ist ein weiteres Zeugnis dieses Verh\u00e4ltnisses, obwohl wir uns hier nicht sonderlich von anderen totalit\u00e4ren Monarchien unterscheiden, welche die Revolution\u00e4re brutal unterdr\u00fcckten.<\/p>\n<p>Beispielhaft ist, dass es in der russischen Mentalit\u00e4t eine absolute Ablehnung jeglicher Reformbestrebungen vorhanden war, was ebenfalls seine Spiegelung in der Geschichte fand. Erinnern wir uns doch an den Mord an Alexander II., der vom Volk als der \u201eBefreier\u201c bezeichnet wurde, einer der wenigen Reformatoren unter den k\u00f6niglichen Pers\u00f6nlichkeiten. Und an den Mord an Stolypin, dessen Reformen Russland unter die fortschrittlichsten Demokratien Europas h\u00e4tten bringen k\u00f6nnen. Eine wichtige Besonderheit der russischen Mentalit\u00e4t war die Psychologie der Gesetzlosigkeit, das Fehlen eines Rechtsverst\u00e4ndnisses der Welt, die v\u00f6llige Ablehnung jeglicher Demokratie. Unter anderem auch deshalb\u00a0hatten die Dekabristen eine Niederlage erlitten, die nach einer konstitutionellen Monarchie strebten, wo das Gesetz \u00fcber der Macht gestanden h\u00e4tte.<\/p>\n<p>Alles wurde durch eine Kraft entschieden, die sich Hinterlist, Heimt\u00fccke, also T\u00e4uschung zu Diensten machte. Das sitzt sehr tief in der russischen gesellschaftlichen Psychologie, bis jetzt.<\/p>\n<p>Damals ist es zu einer logischen Voraussetzung f\u00fcr den Bolschewismus geworden, der eine Quintessenz von allen bis dahin existierenden imperialistischen Tendenzen gemischt mit Unrechtsbewusstsein darstellte\u00a0und der sie auf das Niveau einer sozialen Krankheit brachte. Das bolschewistische Russland stellte eine genauso kranke Gesellschaft dar wie das faschistische Deutschland.<\/p>\n<h2 style=\"text-align: center\"><strong>Die kranke Gesellschaft<\/strong><\/h2>\n<p>Der ber\u00fchmte deutsche Philosoph und Psychologe Erich Fromm, einer der Forscher der Psychologie des Totalitarismus und Faschismus, ver\u00f6ffentlichte 1955 das Buch \u201eGesunde Gesellschaft\u201c, in dem es Zeilen wie gibt: \u201eIn der Vergangenheit bestand die Gefahr darin, dass die Menschen zu Sklaven wurden. Die Gefahr der Zukunft ist, dass die Menschen zu Robotern werden k\u00f6nnen\u201c.<\/p>\n<p>Wir neigen dazu, all die Schuld und Verantwortung auf die herrschende Schicht\u00a0zu verlegen und vergessen dabei, dass all die Gesetzlosigkeit der Anf\u00fchrer mit unserer Zustimmung geschieht. \u201eJedes Volk hat die Regierung, die es verdient,\u201c- schrieb Joseph Marie de Maistre vor zwei Jahrhunderten. Die Gesellschaft, die grausame Verbrechen innerhalb sich selbst zugelassen hatte, und diese nicht geahndet, nicht abgelehnt und nicht als eine mit der Menschlichkeit vereinbare Tat nicht verurteilt hat, kann sich nicht f\u00fcr gesund halten. Sie kann es per Definition nicht sein.<\/p>\n<p>Ich spreche von der Krankheit der Gesellschaft, nicht nur vom politischen Regime. Denn in all den Jahren der Repressionen hat doch irgendjemand die 5 000 000\u00a0Denunziationen geschrieben, nach welchen absolut unschuldige Menschen zu Opfern geworden sind, unter fast v\u00f6lliger Duldung der absoluten Mehrheit der Menschen, vor deren Augen all das passierte. Auf der einen Seite bedeutet die Vernichtung von Millionen Menschen das Ausbluten der Nation, die ihre kl\u00fcgsten, talentiertesten, gewissenhaftesten Vertreter verliert. Auf der anderen ist es eine S\u00fcnde, ein Verbrechen, das sich im kollektiven Bewusstsein widerspiegeln m\u00fcsste.<\/p>\n<p>Die Bewusstwerdung dieses Verbrechens und der eigenen Beteiligung daran ist eine unbeschreiblich schwere psychologische H\u00fcrde. Eine fast unertr\u00e4gliche. Sich davor retten kann man nur auf zwei Arten. Die erste ist all das anzuerkennen und ihm eine dem Geschehen entsprechende Bewertung zu geben, indem man die Verantwortung auf sich nimmt, es verurteilt und schlie\u00dflich &#8211; es b\u00fc\u00dft. Aber auf diesem Weg entsteht ein psychologischer Widerstand: Die Angst vor dieser horrenden Scham und Schuld, die man unweigerlich erleben m\u00fcssen wird, bevor man sich davon erl\u00f6st. \u2028Der zweite Weg ist die Verneinung, die Suche nach einer Rechtfertigung, nach einer Erkl\u00e4rung f\u00fcr all das, der Aufbau eines neuen Weltbildes, das f\u00fcr jeden bequem sein wird, die Erfindung eines Ziels, um dessen willen all das getan wurde. Dabei werden die Schuld und die Scham nicht verschwinden, wie es scheinen k\u00f6nnte, aber indem sie aus dem kollektiven Bewusstsein verdr\u00e4ngt werden, werden sie im Unbewussten weiterleben. Sie werden neue Argumente und neue Taten einfordern, die das k\u00fcnstliche Weltbild der verdrehten Werte best\u00e4tigen. Sie werden neue Opfer fordern.<\/p>\n<p>Heute findet eine R\u00fcckkehr zum Stalinismus statt und wir erinnern uns an seine gruseligsten Seiten. Aber wir machen uns nicht immer Gedanken dar\u00fcber, warum er sich als so z\u00e4hlebig entpuppt hat. Wir m\u00f6chten uns irgendwie nicht daran erinnern, dass eine der sch\u00e4ndlichsten Seiten der russischen Geschichte das Komplott zwischen der UdSSR und Deutschland von 1937 bis 1939 und die faktische Mitwirkung an der Entfachung des Zweiten Weltkrieges ist. \u2028Damals wurde Deutschland nicht von allen als das Imperium des B\u00f6sen wahrgenommen, und die sowjetische Propaganda hat dieses gar als ein uns freundschaftlich gesinntes Land dargestellt. Erst im Juni 9141 wurde klar, mit was f\u00fcr einem Monster wir es zu tun haben. \u2028Aber das Paradoxon bestand darin, dass das stalinistische Russland in keinster Weise besser als das hitlerische Deutschland war, wenn nicht noch schlimmer, denn dieses Regime hat Dutzende Millionen seiner Mitb\u00fcrger vernichtet, was nicht mal Hitler getan hat. Und wenn die Verbrechen des Nationalismus Hitlers eine entsprechende\u00a0Bewertung von der Weltgemeinschaft und von Deutschland selbst bekommen haben, so ist der Stalinismus diesem Los entgangen. Deutschland war f\u00e4hig, diese Krankheit zu \u00fcberwinden, indem es nach dem Zweiten Weltkrieg b\u00fc\u00dfte &#8211; die UdSSR dagegen hat nicht nur keinen derartigen Versuch unternommen, sondern sich nur noch mehr auf totalit\u00e4re Positionen festgelegt . \u2028Die deutsche Aggression gegen die Sowjetunion im Juni 1941 hat faktisch zur Rehabilitierung des Bolschewismus beigetragen, als einer Ideologie eines Landes-Teilnehmers der Anti-Hitler-Koalition, das aktiv gegen Faschismus und Nazismus gek\u00e4mpft hat. An der Tagesordnung stand damals als Hauptfrage, die \u201ebraune Pest\u201c des XX. Jahrhunderts zu besiegen. Der Schaden der kommunistischen Ideologie schien dagegen nicht allzu gro\u00df zu sein. \u201e\u00dcber Sieger urteilt man nicht\u201c und \u201eDer Krieg begleicht alle Rechnungen\u201c &#8211; unter solchen Slogans ist die Krankheit aus der akuten Phase in eine chronische \u00fcbergegangen und hat sich in der gesellschaftlichen Psychologie festgesetzt (man m\u00f6chte glauben, dass dies nicht irreversibel ist&#8230;).<\/p>\n<p>Zur Reue hat auch weder die Niederlage im Kalten Krieg noch der darauffolgende Zerfall der UdSSR gef\u00fchrt. F\u00fcr uns wurde dieser Zerfall zu etwas \u00c4hnlichem, was f\u00fcr Deutsche die Niederlage Deutschlands im Ersten Weltkrieg war. Und so, wie es in Deutschland zur Entstehung des Nazismus gef\u00fchrt hat, so haben wir in Russland nun \u00e4hnliche Resultate. Der Informationskrieg, der zur Realisation imperialistischer Ambitionen entfacht wurde, hat in erster Linie die B\u00fcrger Russlands \u00fcberfallen. Sie sind Opfer eines neuen sozialen Experiments geworden.<\/p>\n<p>Man kann hier folgende Schlussfolgerung ziehen:<\/p>\n<p><i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\"><b>Die bedeutendste Folge des Informationskrieges ist die fast irreversible Transformation des gesellschaftlichen Bewusstseins eines ganzen Landes.<\/b><\/i><\/p>\n<p>Der Informationskrieg hat nicht blo\u00df\u00a0zu einer propagandistischen Gehirnw\u00e4sche gef\u00fchrt. Er hat das Rezidiv einer alten Krankheit hervorgerufen, die unsere Gesellschaft vor fast 100 Jahren befallen hatte (Genauer: hat diese wieder mal aus der chronischen in eine akute Phase \u00fcberf\u00fchrt). Man kann sie verschieden nennen: Bolschewismus, Stalinismus, imperialistisches Syndrom, russischer Nazismus, orthodoxer Faschismus oder sonst wie.<\/p>\n<p>Es sind nicht verschiedene Erscheinungen &#8211; das sind im Grunde Symptome einer Krankheit, auch wenn sie verschiedenen Ideologien entsprungen sind, faktisch &#8211; Antipoden: kriegerischer Atheismus und kriegerische Orthodoxie, Kommunismus und Faschismus. Obwohl die Extremen, wie bekannt, zusammenfinden.<\/p>\n<p>Aber der jetzige Rezidiv ist einer von viel schwererer Form und unterscheidet sich von der Krankheitsphase des Stalinismus durch eine deutlich erkennbare Faschistisierung des gesellschaftlichen Bewusstseins. Wie <a href=\"https:\/\/informnapalm.org\/de\/?s=Lew+SChlossberg&amp;submit=Search\">Lew Schlossberg<\/a> es treffend formulierte: <a href=\"http:\/\/inforesist.org\/segodnya-rossiya-eto-strana-idealno-gotovaya-k-fashizmu\/\">\u201eHeute ist Russland ein Land, das ideal auf Faschismus vorbereitet ist\u201c.<\/a><\/p>\n<h2 style=\"text-align: center\"><strong>Von Bu\u00dfe zur Heilung<\/strong><\/h2>\n<p>Die Heilung von dieser Krankheit kann nur durch Bu\u00dfe geschehen. Eine tiefe und restlose Bu\u00dfe. Und diese ist ohne die Anerkennung der kollektiven Verantwortung f\u00fcr die ganze Geschichte des letzten Jahrhunderts (und vielleicht sogar noch mehr) unm\u00f6glich. Das ist eine sehr schwere Aufgabe, denn man wird durch eine gro\u00dfe Schande gehen und eine Last der schwersten Schuld auf sich nehmen m\u00fcssen. Wenn man es nicht tut, ist der einzige Weg das Scham- und Schuldgef\u00fchl zu vermeiden, die Wahrheit zu verneinen und die objektive Realit\u00e4t mit verdrehten moralischen Werten mit Hilfe von Mechanismen der projizierten Identifikation umzuf\u00e4rben.<\/p>\n<p>In der Geschichte der UdSSR gab es zwei Versuche der Bu\u00dfe: w\u00e4hrend des \u201eTauwetters\u201c unter Chruschtschower und in der Zeit der Perestroika Gorbatschows. Kaum hatte sie angefangen, wurden sie jedoch schon wieder zusammengerollt, und es folgte die R\u00fcckkehr zum Stalinismus. Das erste Mal hat man die ganze Verantwortung faktisch auf Stalin geschoben und auf seine engsten hochrangigen Henker des \u201ePers\u00f6nlichkeitskults\u201c (Jeschow, Beria). Das ist wie wenn im N\u00fcrnberger Prozess nur Hitler beschuldigt worden w\u00e4re. Darum wurde der XX. Parteitag der KPdSU nicht zum N\u00fcrnberger Tribunal des Stalinismus und konnte es auch gar nicht werden. Obwohl er eine kolossale historische Bedeutung hatte (Die Rehabilitierung und Befreiung von Hunderttausenden Unschuldigen aus den Lagern), war es eine unvollendete Heilung, die sp\u00e4ter zu Rezidiven f\u00fchrte.<\/p>\n<p>Echte Reue kam auch nicht w\u00e4hrend der Perestroika-Zeit auf, obwohl die Hoffnung bestand, dass es so sein wird. Unvollst\u00e4ndige Bu\u00dfe wird keine Befreiung bringen. Sie ist wie ein nicht komplett herausgeschnittenes Krebsgeschw\u00fcr, das neue Metastasen bilden kann und den scheinbar geheilten Organismus mit einer neuen Krankheit befallen kann, manchmal sogar schwerer als der zuvor. Und wenn man das Unkraut nicht mit der Wurzel herausrei\u00dft, wird es wieder auskeimen und die Nutzpflanzen t\u00f6ten.<\/p>\n<p>Die parallele Realit\u00e4t, die durch die Kremlpropaganda erschaffen wurde, ist ein wunderbarer psychologischer Schutz vor dem traumatisierten Bewusstsein des Aggressors, das ist eine Erl\u00f6sung von der Notwendigkeit der Bu\u00dfe, von der \u00dcbernahme der Verantwortung, vom Schulderleben und jeglichen anderen Regungen des Gewissens. Die Schande der Bewusstwerdung der Ungeheuerlichkeit der zu rechtfertigenden Verbrechen kann man stolz\u00a0mit \u201eOpas haben gek\u00e4mpft\u201c und \u201eAufstehen von den Knien\u201c, mit\u00a0Erhabenheit der \u201eRussischen Welt\u201c und anderen Mythen ersetzen, die aus der parallelen Antiwelt andere Realit\u00e4ten verdr\u00e4ngen, die wegen ihrer scheu\u00dflichen Wahrheit nicht zu ertragen sind.<\/p>\n<p>Die deutsche Nation ist da durchgegangen, auch wenn es ihr ganz und gar nicht leicht gefallen ist. Dieser Prozess endete nicht mit N\u00fcrnberg und erstreckte sich auf mehrere Jahrzehnte.\u00a0Die niederschmetternde Niederlage im Zweiten Weltkrieg, seine\u00a0nationale Trag\u00f6die, hat\u00a0Deutschland, wie paradox es auch ist, dabei geholfen. Braucht\u00a0denn Russland nicht auch eine nicht weniger niederschmetternde Niederlage, um derartiges Fegefeuer durchzustehen?<\/p>\n<p>Wenn man nach dem Geschehen der letzten Monate urteilt, wird genau so ein Szenario absolut wahrscheinlich.<\/p>\n<p>* * *<\/p>\n<p>Wie kann man dem katastrophalen Geschehen vorbeugen, um so mehr &#8211; der Gefahr einer thermonuklearen Weltkatastrophe? Wie kann man den Informations-Frankenstein aufhalten? Und ist es \u00fcberhaupt m\u00f6glich?<\/p>\n<p>Man muss etwas im Bewusstsein der Menschen \u00e4ndern, sie zwingen zu verstehen, dass die Medienpropagandisten die realen Schuldigen an den tragischen Ereignissen sind, die unter der Einwirkung der Propaganda stattfinden, und dass sie mit Kriegsverbrechern gleichgesetzt werden m\u00fcssen. Man muss die ungesunde kollektive Psyche der Gesellschaft heilen, die parallelen Realit\u00e4ten transformieren, die\u00a0im Stande sind, Menschen massenhaft zu t\u00f6ten.<\/p>\n<p>Diese Aufgaben sind nicht weniger wichtig, als die Probleme der Bewaffnung, die wirtschaftlichen Reformen, der Kampf mit der Korruption. Dar\u00fcber m\u00fcssen sich die Politiker und die Wissenschaftler (in erster Linie- soziale und politische Psychologen) den Kopf zerbrechen. Aber daf\u00fcr braucht man wenigstens die Entstehung eines Bedarfs nach ihrer L\u00f6sung.<\/p>\n<p>All die Gespr\u00e4che dar\u00fcber, dass es noch \u201enicht an der Zeit\u201c ist, dass es wichtigere Aufgaben gibt, sind belanglos, denn ohne die fachm\u00e4nnische Informationspolitik wird die L\u00f6sung der wichtigen Staatsaufgaben unm\u00f6glich und wird viel gr\u00f6\u00dfere Ressourcen einfordern. All die \u00dcberlegungen dar\u00fcber, dass wir keine Mittel dazu haben sind verbrecherisch gef\u00e4hrlich. Das Ausbleiben\u00a0dieses Vorgehens wird uns tausend Mal mehr kosten.<\/p>\n<p>K\u00fcrzlich\u00a0wurde ein Informationsministerium geschaffen, in dem eine Abteilung f\u00fcr Informationssicherheit gebildet wurde (na endlich!). Es scheint, als ob die Sache in Schwung gekommen ist. Aber diese Beh\u00f6rde besch\u00e4ftigt sich \u00fcberhaupt nicht mit den Problemen der Medienraum-Psychologie, sie verstehen nicht, dass dies die Schl\u00fcsselprobleme sind, denn die Parallelrealit\u00e4ten existieren in der Psyche der Menschen. Aber noch interessanter ist der Fakt, dass es \u00e4hnliche Strukturen auch fr\u00fcher schon gab: Das ist die Abteilung f\u00fcr Informationspolitik des Au\u00dfenministeriums der Ukraine und den Rat f\u00fcr Fragen der Informationspolitik beim Pr\u00e4sidenten der Ukraine, wie auch die Abteilung f\u00fcr Informationssicherheit beim SBU, die schon 2011 schaffen wurde. Was haben sie denn bis jetzt gemacht?<\/p>\n<p>Man muss verstehen, dass der Informationskrieg bereits seit 15 Monaten l\u00e4uft. Und auf einen Krieg muss man mit ad\u00e4quaten Mitteln antworten. Man muss ununterbrochen gegen die Desinformation k\u00e4mpfen, indem man die parallele Realit\u00e4t der informativen Antiwelt zerst\u00f6rt. Aber die Gegenpropaganda darf nicht dieselben Waffen verwenden.<\/p>\n<p>Der L\u00fcge muss man die Wahrheit entgegenstellen. Man muss verstehen (und das ist sehr erfreulich), dass die Desinformation, die in einem Informationskrieg die Hauptwaffe ist, eine \u201eschnellverderbliche\u201c Ware ist. Mit der Zeit, unter dem Druck der Wahrheit, oder sogar einfach nur unter dem Druck des gesunden Menschenverstandes, geschieht ihr nat\u00fcrlicher \u201eHalbzerfall\u201c. Man muss sie permanent mit einer neuen ersetzen, darum braucht man immer neuere Geschichten, Videos, \u201eZeugnisse\u201c der Pseudozeugen. Die Wahrheit dagegen, die man der L\u00fcge entgegenstellen kann, hat faktisch eine unbegrenzte Haltbarkeit. Mehr noch, wenn es die Pr\u00fcfung der Zeit besteht, wird es, wie ein guter Wein oder Cognac, noch besser und robuster.<\/p>\n<p>Fr\u00fcher oder sp\u00e4ter wird die Wahrheit siegen und die parallele Realit\u00e4t zerst\u00f6ren. Und je grandioser die Konstruktion war, um so niederschmetternder wird die Katastrophe. Und auf den Tr\u00fcmmern der alten \u201einformativen Antiwelt\u201c wird eine neue lebendige Realit\u00e4t aufkeimen, so wie einst auf den Tr\u00fcmmern des infolge von L\u00fcge und Unzucht untergegangenen R\u00f6mischen Imperiums eine neue Europ\u00e4ische Zivilisation entstand.<\/p>\n<hr \/>\n<p><em>Autor: <strong><a href=\"https:\/\/www.facebook.com\/pavelgorn\">Pawel Gornostai<\/a><\/strong>, Dr. der Psychologiewissenschaften; <a href=\"http:\/\/gorn.kiev.ua\">Website des Autors<\/a>; \u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/Kaspijka\">Irina Schlegel.<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wei\u00dft Du denn, worin wir stark sind, Basmanow? Nicht mit dem Heer, nein, nicht mit der Hilfe&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3935,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[98,131,707,132],"tags":[190,232,106,12,13],"class_list":["post-3933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-expertenmeinungen","category-gesellschaft","category-zeitdokumente","tag-informationskrieg","tag-kremlpropaganda","tag-propaganda","tag-russland","tag-ukraine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Information-Frankenstein oder reale Folgen des Informationskrieges - InformNapalm (Deutsch)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Information-Frankenstein oder reale Folgen des Informationskrieges - InformNapalm (Deutsch)\" \/>\n<meta property=\"og:description\" content=\"Wei\u00dft Du denn, worin wir stark sind, Basmanow? Nicht mit dem Heer, nein, nicht mit der Hilfe...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/\" \/>\n<meta property=\"og:site_name\" content=\"InformNapalm (Deutsch)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/informnapalm24\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/oxanatinko\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-01T20:05:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-09T11:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1470\" \/>\n\t<meta property=\"og:image:height\" content=\"1469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"22\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/\"},\"author\":{\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\",\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a\"},\"headline\":\"Information-Frankenstein oder reale Folgen des Informationskrieges\",\"datePublished\":\"2015-03-01T20:05:59+00:00\",\"dateModified\":\"2017-10-09T11:27:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/\"},\"wordCount\":4311,\"image\":{\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg\",\"keywords\":[\"Informationskrieg\",\"Kremlpropaganda\",\"propaganda\",\"Russland\",\"Ukraine\"],\"articleSection\":[\"Aktuell\",\"Expertenmeinungen\",\"Gesellschaft\",\"Zeitdokumente\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/\",\"url\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/\",\"name\":\"Information-Frankenstein oder reale Folgen des Informationskrieges - InformNapalm (Deutsch)\",\"isPartOf\":{\"@id\":\"https:\/\/informnapalm.org\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg\",\"datePublished\":\"2015-03-01T20:05:59+00:00\",\"dateModified\":\"2017-10-09T11:27:47+00:00\",\"author\":{\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a\"},\"breadcrumb\":{\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage\",\"url\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg\",\"contentUrl\":\"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg\",\"width\":1470,\"height\":1469},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/informnapalm.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Information-Frankenstein oder reale Folgen des Informationskrieges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/informnapalm.org\/de\/#website\",\"url\":\"https:\/\/informnapalm.org\/de\/\",\"name\":\"InformNapalm (Deutsch)\",\"description\":\"OSINT, HUMINT, Analytik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/informnapalm.org\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a\",\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/informnapalm.org\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g\",\"caption\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e\"},\"sameAs\":[\"https:\/\/informnapalm.org\/\",\"https:\/\/www.facebook.com\/oxanatinko\",\"https:\/\/x.com\/oxana_tinko\"],\"url\":\"https:\/\/informnapalm.org\/de\/author\/oxana\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Information-Frankenstein oder reale Folgen des Informationskrieges - InformNapalm (Deutsch)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/","og_locale":"de_DE","og_type":"article","og_title":"Information-Frankenstein oder reale Folgen des Informationskrieges - InformNapalm (Deutsch)","og_description":"Wei\u00dft Du denn, worin wir stark sind, Basmanow? Nicht mit dem Heer, nein, nicht mit der Hilfe...","og_url":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/","og_site_name":"InformNapalm (Deutsch)","article_publisher":"https:\/\/www.facebook.com\/informnapalm24","article_author":"https:\/\/www.facebook.com\/oxanatinko","article_published_time":"2015-03-01T20:05:59+00:00","article_modified_time":"2017-10-09T11:27:47+00:00","og_image":[{"width":1470,"height":1469,"url":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg","type":"image\/jpeg"}],"author":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","twitter_misc":{"Verfasst von":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","Gesch\u00e4tzte Lesezeit":"22\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#article","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/"},"author":{"name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a"},"headline":"Information-Frankenstein oder reale Folgen des Informationskrieges","datePublished":"2015-03-01T20:05:59+00:00","dateModified":"2017-10-09T11:27:47+00:00","mainEntityOfPage":{"@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/"},"wordCount":4311,"image":{"@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg","keywords":["Informationskrieg","Kremlpropaganda","propaganda","Russland","Ukraine"],"articleSection":["Aktuell","Expertenmeinungen","Gesellschaft","Zeitdokumente"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/","url":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/","name":"Information-Frankenstein oder reale Folgen des Informationskrieges - InformNapalm (Deutsch)","isPartOf":{"@id":"https:\/\/informnapalm.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage"},"image":{"@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage"},"thumbnailUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg","datePublished":"2015-03-01T20:05:59+00:00","dateModified":"2017-10-09T11:27:47+00:00","author":{"@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a"},"breadcrumb":{"@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#primaryimage","url":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg","contentUrl":"https:\/\/informnapalm.org\/de\/wp-content\/uploads\/sites\/3\/2015\/03\/dali.jpg","width":1470,"height":1469},{"@type":"BreadcrumbList","@id":"https:\/\/informnapalm.org\/de\/information-frankenstein-oder-reale-folgen-des-informationskrieges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/informnapalm.org\/de\/"},{"@type":"ListItem","position":2,"name":"Information-Frankenstein oder reale Folgen des Informationskrieges"}]},{"@type":"WebSite","@id":"https:\/\/informnapalm.org\/de\/#website","url":"https:\/\/informnapalm.org\/de\/","name":"InformNapalm (Deutsch)","description":"OSINT, HUMINT, Analytik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informnapalm.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/96ae00c3b1d58255bc6559a1b070bf9a","name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/informnapalm.org\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1216905db9b422860abe5e7af6a2cea590585d58c81a845d5f1b514360804f2?s=96&d=blank&r=g","caption":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0422i\u043d\u044c\u043a\u043e"},"sameAs":["https:\/\/informnapalm.org\/","https:\/\/www.facebook.com\/oxanatinko","https:\/\/x.com\/oxana_tinko"],"url":"https:\/\/informnapalm.org\/de\/author\/oxana\/"}]}},"views":3336,"post_src":"<p style=\"text-align: right\" align=\"RIGHT\"><i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\">Wei\u00dft Du denn, worin wir stark sind, Basmanow?<\/i><\/p>\r\n<p style=\"text-align: right\" align=\"RIGHT\"><i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\">Nicht mit dem Heer, nein, nicht mit der Hilfe Polens,<\/i><\/p>\r\n<p style=\"text-align: right\" align=\"RIGHT\"><i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\">sondern mit der Meinung! Ja! Mit der Meinung unseres Volkes.<\/i><\/p>\r\n<p style=\"text-align: right\" align=\"RIGHT\">A.Puschkin \u201eBoris Godunow\u201c<\/p>\r\n\u00dcber den Informationskrieg spricht derzeit vielleicht nur ein Faulpelz nicht (wobei vieles, was im Medienraum passiert, richtiger als \u201eInformationsterrorismus\u201c zu bezeichnen w\u00e4re, wie es <a href=\"https:\/\/informnapalm.org\/de\/w-pastuchow-zu-spaet-zu-schreien-boris-nemzow-wurde-ermordet\/\">Boris Nemzow<\/a> formuliert hat). Russland agiert in diesem Krieg sehr raffiniert, indem es seine Taktik permanent \u00e4ndert, auf die Situation operativ reagiert und immer neuere Kr\u00e4fte in den Kampf wirft. Alles wie im realen Krieg.\r\n\r\n<a href=\"https:\/\/informnapalm.org\/de\/15-jahre-geheimkrieg-putins-gegen-die-ukraine\/\">Er wird gegen die Ukraine schon mehrere Jahre gef\u00fchrt<\/a>, wom\u00f6glich all die Jahre der Unabh\u00e4ngigkeit, und hat in letzter Zeit einen besonderen Zynismus erreicht.\r\n\r\nWir verlieren weiterhin Stellung f\u00fcr Stellung und Widerstand gibt es nicht genug, oft gibt es gar keinen. Und das Wichtigste: bis jetzt hat noch immer keine \u201eInformations-ATO\u201c angefangen.\r\n\r\nWir wehren uns durch einzelne Auftritte von Politikern, Publizisten, Journalisten, Diskussionen beim FB, Talkshows im Fernsehen. In letzter Zeit gibt es sogar Probleme mit Talkshows, es scheint ganz so, als ob die Meinungsfreiheit jemandem an der Macht\u00a0ganz und gar nicht gef\u00e4llt. Den Krieg gegen die Informationsmonster f\u00fchren nur freiwillige Aktivisten. Wenn man hier eine milit\u00e4rische Analogie zieht, handelt es sich umeine Abwehr durch einzelne K\u00e4mpfer mit Gewehren und Maschinenpistolen gegen eine milit\u00e4rische Armada mit Panzern, Luftwaffe und Raketen. Das Kr\u00e4fteverh\u00e4ltnis ist ziemlich ungleich. Und viele unsere \u201eB\u00fcrger\u201c (ich kann das nicht ohne Anf\u00fchrungszeichen schreiben) k\u00e4mpfen in diesem Krieg noch immer auf der Seite des Aggressors.\r\n\r\nVon allen \u201emateriellen\u201c Verlusten sind zum heutigen Tag zwei die wichtigsten: 1. Die\u00a0<a href=\"https:\/\/informnapalm.org\/de\/krimer-kantstein-ein-jahr-spaeter-einzelheiten-der-russischen-sonderoperation-zur-krim-annexion\/\">Okkupation der Krim<\/a>\u00a0und\u00a02. Der Krieg im Donbass, der sich in eine humanit\u00e4re Katastrophe f\u00fcr die ganze Region hin\u00fcberw\u00e4chst. Man sollte anerkennen, dass die Einnahme und Annexion der Krim ein grelles Beispiel des Sieges im Informationskrieg ist. Sie wird zweifellos in alle Lehrb\u00fccher zur <a href=\"https:\/\/informnapalm.org\/de\/die-psychologie-eines-manipulators-ist-die-psychologie-eines-moerders\/\">Psychologie der Propaganda<\/a>\u00a0eingehen. Aber genauso offensichtlich ist, dass die Krim zur\u00fcckzuholen\u00a0ohne Gegeninformationskampf sehr schwierig wird, wenn es denn \u00fcberhaupt m\u00f6glich ist.\r\n\r\nWir haben nicht nur reale geografische Regionen verloren. Wir haben riesige Gebiete im Informationsraum verloren, die sich mit \u201eparallelen Antiwelten\u201c gef\u00fcllt haben, gegen welche wir keinerlei Ma\u00dfnahmen ergreifen. Diese Niederlagen sind prim\u00e4r, sie sind der Grund aller weiteren materiellen Verluste. Wenn wir nicht die \u201eInformationsterritorien\u201c zur\u00fcckgewinnen, die in den K\u00f6pfen von Millionen Menschen existieren, werden wir auch keine geografischen Territorien zur\u00fcckerobern k\u00f6nnen.\r\n<h2 style=\"text-align: center\"><strong>Putin ist der moderne Frankenstein<\/strong><\/h2>\r\nEinmal bin ich im Internet auf die folgende Formel gesto\u00dfen (leider kenne ich den Autor nicht): <strong>\u201eDie halbe Wahrheit + die halbe Wahrheit = L\u00fcge\u201c<\/strong>. Die Formel ist nicht nur sch\u00f6n, sie spiegelt das Wesen der Erschaffung einer \u201ehochqualitativen L\u00fcge\u201c genial wieder, die einwandfrei funktioniert und in den K\u00f6pfen der Menschen einen festen Platz im System ihrer \u00dcberzeugungen einnimmt. Sie ist bei weitem effektiver als klare Fakes in der Art von \u201egekreuzigten Jungs\u201c und \u201ehingerichteten Gimpeln\u201c. Die Kraft dieser L\u00fcge besteht darin, dass sie eben keine leere Erfindung ist, sondern aus einzelnen Thesen erschaffen wird, die an sich nicht gelogen sind. Sie sind leicht erkennbar und dienen als \u201eSchl\u00fcssel\u201c zur Anbindung dieser L\u00fcge an die Wahrheit. Das ist dasselbe wie die Tatsache, dass man aus \u201ewahrhaftigen\u201c St\u00fcckchen eines Mosaiks ein Bild zusammenlegen kann, das vom Sinn und Inhalt her seinen Einzelteilen diametral entgegengesetzt ist.\r\n\r\nIm bekannten Roman der englischen Schriftstellerin Mary Shelley \u201eFrankenstein oder der moderne Prometheus\u201c erschafft der Held Victor Frankenstein ein menschen\u00e4hnliches Monster von einer Riesengr\u00f6\u00dfe und Kraft, das sp\u00e4ter aufh\u00f6rt, sich unterzuordnen und sich an seinem Erschaffer f\u00fcr sein Aussehen r\u00e4cht.\r\n\r\nEs t\u00f6tet Familienmitglieder von Frankenstein und f\u00fchrt schlie\u00dflich zu seinem eigenen Tod. Interessant ist hier die Tatsache, dass das Monster aus Einzelteilen der realen menschlichen K\u00f6rpern zusammengesetzt wurde. Das ist eine Art \u201eWunder der Transplantation\u201c, aber nicht zur Lebensrettung eines Menschen durch den Austausch eines defekten Organs, sondern mit dem Ziel, ein anderes Objekt (Subjekt) mit g\u00e4nzlich neuen Eigenschaften zu erschaffen.\r\n\r\nEtwas \u00e4hnliches ist auch im Informationsraum passiert.\r\n\r\nDie propagandistische Maschine des Kremls produziert nicht einfach nur \u201einformativ-propagandistischen Geschosse\u201c, die die Psyche eines Menschen besch\u00e4digen. Sie hat eine komplette Parallelrealit\u00e4t erschaffen, in der wie in einem separaten Land Dutzende Millionen Menschen leben.\r\n\r\nNichts daran w\u00e4re neu (denn Parallelrealit\u00e4ten hat man auch in der Vergangenheit erschaffen, \u00fcberdies auch lange vor der Erfindung des Fernsehens und Internets), wenn es hier nicht einen Umstand g\u00e4be: Diese neue Realit\u00e4t hat eine ungeheuerliche Kraft entfaltet und begann faktisch, ein selbstst\u00e4ndiges Leben zu f\u00fchren. Wie das Monster aufgeh\u00f6rt hat, sich Frankenstein unterzuordnen, so hat auch diese monstr\u00f6se Realit\u00e4t aufgeh\u00f6rt, sich ihrem Hauptarchitekten Putin unterzuordnen.\r\n\r\nIn dieser Realit\u00e4t befinden sich Dutzende Millionen Russen, darin sind Hunderttausende Donbas-Einwohner versunken (in erster Linie auf den Territorien, die von den \u201eDVR-LVR\u201c kontrolliert werden). Der Unterschied zwischen ihnen besteht darin, dass die Erstgenannten ein\u00a0alternative Alltagsrealit\u00e4t\u00a0zu ihrer Verf\u00fcgung haben, bei den anderen aber der reale und der virtuelle Informationsraum zu einem Ganzen verschmolzen sind, und sie sich nun im Zentrum des surrealen \u201eTheater des Absurdes\u201c befinden. Wenn man hier eine milit\u00e4rische Metapher anwendet, haben sie sich im Wirkungsherd der informativen Massenvernichtungswaffen wiedergefunden und sind im Grunde Verwundete (informativ gequetscht).\r\n\r\nDie Tatsache, dass die Informationswaffe t\u00f6ten kann und das im buchst\u00e4blichen Sinne, ist objektiv bewiesen, mit einer mathematischen Genauigkeit. Die Geschichte des Genozids in Ruanda 1994, der nach verschiedenen Angaben das Leben von 500 000 bis zu 1 000 000 Menschen weggefegt hat, demonstriert sehr beispielhaft die Rolle der Radiostation \u201eRadio der tausend H\u00fcgel\u201c beim Entfachen von nationalem Hass und mit Aufrufen zur Vernichtung der ethnischen Minderheit. Dem Harvard-\u00d6konomisten David Janagisawa-Drott ist \u00a0derBeweis gelungen, dass in Gegenden, in denen diese Radiostation nicht empfangen werden konnte, die Anzahl der wegen Mordes Verurteilten um 62-69% geringer war, als dort, wo diese Sendungen empfangen wurden. Die Zahlen sind mehr als \u00fcberzeugend und beweisen die Verantwortlichkeit der Medien f\u00fcr den Tod von Hunderttausenden Menschen.\r\n\r\nDar\u00fcber kann man im Artikel<a href=\"http:\/\/snob.ru\/selected\/entry\/81673\"> \u201eTausend Tote f\u00fcr Tausend Worte. Wie die Propaganda in Ruanda funktionierte\u201c<\/a> nachlesen. \u00dcbrigens wurden die Moderatoren dieser Radiostation zu jahrelangen Haftstrafen verurteilt. Und dabei ist das Fernsehen\u00a0im Dienst der Propaganda weitaus effektiver als das Radio. Dar\u00fcber sollte man ernsthaft nachdenken.\r\n\r\nDie Haupteigenschaft des Informationskrieges Russlands ist die Verwendung moderner Psychologietechnologien (solche wie zum Beispiel die neuro-linguistische Programmierung) und ein nie zuvor gesehenes Ausma\u00df der L\u00fcge.\r\n\r\nMan sollte daran denken, dass die Resultate der Ansteckung mit den \u201eToxinen\u201c der Desinformation f\u00fcr die menschliche Psyche sehr dauerhaft sind, und ihre Folgen sogar nach ihrer Neutralisation weiter existent bleiben. Wenn man dies ber\u00fccksichtigt, kann man als eine wichtige Folge des modernen Informationskrieges die Tatsache betrachten, dass die von ihm erschaffene Realit\u00e4t nicht mehr zur\u00fcckzutransformieren, umzulenken, ja nicht einmal zu lokalisieren ist, und noch weniger ist diese zu veredeln, \u201ewahrhaftiger zu machen\u201c, zu entsch\u00e4rfen. Und dabei \u00fcbersteigt die Toxizit\u00e4t der L\u00fcge ja alle m\u00f6glichen Grenzen und hat ein Niveau erreicht, das nur mit Massenvernichtungswaffen zu vergleichen ist, und nach manchen Bewertungen sogar diese l\u00e4ngst \u00fcbertroffen hat. Eben darum ist Putin nun zu einer Geisel der von ihm selbst erschaffenen Situation geworden und kann seinen Weg ganz einfach nicht mehr verlassen. \u2028Er kann keinen allumfassenden Krieg gegen die Ukraine beginnen (wegen Sanktionen, mangelnder Ressourcen, Krise und vieler weiterer objektiver und subjektiver Gr\u00fcnde). Aber er kann auch nicht mehr anhalten, denn das von ihm erschaffene informativ-propagandistische Monster treibt ihn zum n\u00e4chsten Amok, es lechzt nach neuem Blut und geht keinerlei Kompromisse ein. Sich ihm nicht unterzuordnen ist Selbstmord (und wom\u00f6glich nicht nur ein politischer) - das Monster wird sich an seinem Erschaffer auf die raffinierteste Art r\u00e4chen (und es geschieht bereits).\u00a0Sich unterzuordnen ist der Weg zur Insania, in der aus Verzweiflung die schrecklichsten Schritte unternommen werden k\u00f6nnten, bis hin zur Anwendung von Atomwaffen.\r\n<h2 style=\"text-align: center\"><strong>Zwei Arten des historischen Traumas: Trauma des Opfers und Trauma des Aggressors<\/strong><\/h2>\r\nIn der modernen sozialen Psychologie von gro\u00dfen Gruppen wird aktiv eine Theorie des kollektiven oder historischen Traumas entwickelt.\r\n\r\nWir gehen von der Annahme aus, dass au\u00dfer dem individuellen Bewussten und dem Unbewussten als Charakteristikum von gro\u00dfen Menschengruppen noch das kollektive Bewusste und Unbewusste existiert. Und mit ihm existieren auch solche Erscheinungen wie ein kollektives Trauma, kollektiver Stolz, kollektive Scham. In letzter Zeit widmet sich auch die Publizistik diesem Thema, schauen Sie doch bitte zum Beispiel die Artikel von Ilja Kukulin <a href=\"http:\/\/postnauka.ru\/faq\/26580?_utl_t=fb\">\u201eHistorisches Trauma als eine kulturelle Erscheinung\u201c<\/a> und Michail Jampolski <a href=\"http:\/\/www.colta.ru\/articles\/specials\/6088\">\u201eWie urteilt man \u00fcber Sieger?\u201c<\/a>\r\n\r\nSo wird die Massenpsychologie des modernen Russland, die der heutigen Politik zugrunde liegt, mit dem Trauma des Imperiumszerfalls erkl\u00e4rt, was mit Versuchen, dieses zu restaurieren, kompensiert wird (die Idee der \u201eRussischen Welt\u201c), das \u201eAufstehen von den Knien\u201c, die Ausbeutung des Konzepts der Weltverschw\u00f6rung etc.\r\n\r\nMeiner Meinung nach ist es falsch zu denken, dass dem kollektiven Trauma nur die Opfer unterlegen sind. Obwohl es diesem Thema viele Untersuchungen gewidmet sind, sind bei weitem nicht alle Aspekte verst\u00e4ndlich. So hat man sehr wenig analysiert, was denn mit der kollektiven Psychologie der Aggressoren geschieht, inwieweit diese Erfahrung f\u00fcr sie traumatisch wird. Das einzige Thema, das wohl gestreift wurde, ist Deutschland nach dem Zweiten Weltkrieg, aber das ist ein Schicksal vom Halbaggressor-Halbopfer, das eine Niederlage in diesem Krieg erlitt. Wahrscheinlich darf man das Problem nicht nur von einem einzigen Standpunkt aus untersuchen, denn die Rollen des \u201eAggressoren\u201c und des \u201eOpfers\u201c sind oft gegenseitig verflochten, sie k\u00f6nnen ihre Pl\u00e4tze tauschen, wie im dramatischen Dreieck von Karpman.\r\n\r\nWenn man diese Prozesse am Beispiel Russlands betrachtet (genauer \u2013 der Sowjetunion), so werden wir viele Fakten der kollektiven Traumatisierung durch die eigene Aggressivit\u00e4t sehen, wo die Gesellschaft gleichzeitig als ein Opfer und ein Aggressor auftritt. In erster Linie ist Russland (genauer- die Sowjetunion) ein Staat, der im Laufe von 50 Jahren die Bl\u00fcte seiner Nation vernichtete und faktisch einen intellektuellen und moralischen Genozid beging.\r\n\r\nAngefangen mit dem \u201eRoten Terror\u201c der 1920er Jahre, dem B\u00fcrgerkrieg und der ersten Emigrationswelle (in welcher die Bl\u00fcte der Nation ausgereist war: Wissenschaftler, Philosophen). Sp\u00e4ter gab es noch blutigere Ereignisse (Exekutionen und Zwangsarbeit der 1930er), Krieg, im Feuer dessen beste Vertreter der Nation nicht allein durch Feindesh\u00e4nde gefallen sind. Sehr beispielhaft ist das Verh\u00e4ltnis zu jenen, die aus der Gefangenschaft ausgebrochen waren, die die deutschen Konzentrationslager \u00fcberlebt hatten. In derselben Zeit wurden auch die Deportationen und der Genozid an ganzen V\u00f6lkern begangen (Tschetschenen, Krimtataren, Wolga-Deutschen und anderen). Eine der schrecklichsten Seiten dieser Geschichte ist der Holodomor der 1930er, der k\u00fcnstlich, ohne objektive Gr\u00fcnde (wie zum Beispiel Missernten) erschaffen wurde. Au\u00dfer der physischen Vernichtung wurden viele Menschen aus dem Land vertrieben oder sie haben es selbst verlassen, um sich vor Repressionen zu retten oder vor unmenschlichen Existenzbedingungen zu fl\u00fcchten.\r\n<h2 style=\"text-align: center\"><strong>Historische Gr\u00fcnde<\/strong><\/h2>\r\nH\u00f6chstwahrscheinlich hat das alles nicht erst 1917 angefangen, sondern besitzt tiefer gehende historische Wurzeln. Die Geschichte Russlands ist zumindest in den letzten 500 Jahren durch eine expansive Au\u00dfenpolitik gekennzeichnet (eine w\u00fcrdige Weiterf\u00fchrung von\u00a0Traditionen der Goldenen Horde). Faktisch stellt die ganze russische Geschichte die Eroberung von immer neueren Territorien dar, die dem unermesslichen Imperiums miangeschlossen wurden.\r\n\r\nAllein in den letzten 200\u00a0Jahren geschahen die Annexion der rechtsufrigen Ukraine, des Territoriums des Krimer Khanats, Georgiens (Ende 18.- Anfang 19. Jahrhunderts) , sp\u00e4ter gab es noch den Kaukasus-Krieg und die Unterjochung der V\u00f6lker des Nordkaukasus.\r\n\r\nDie zweite Komponente ist das Verh\u00e4ltnis des Staates zu seinem eigenen Volk, das sich traditionell auf der Ebene von Sklaven befand (die Leibeigenschaft existierte bei uns bis 1861 und wurde w\u00e4hrend der sowjetischen \u00c4ra faktisch wiederhergestellt). Dasselbe Verh\u00e4ltnis hatte man auch zu russischen Genies - man braucht sich nur an das tragische Schicksal von Puschkin, Lermontow, Gribojedow und vielen anderen zu erinnern. Nicht weniger tragisch verlief auch das Schicksal der Wissenschaftler und Erfinder, das wunderbar in der Gestalt von Lewscha in der Novelle von Leskow wiedergespiegelt wird. Lomonossow war wahrscheinlich eine gl\u00fcckliche Ausnahme, indem er faktisch in eine Ikone verwandelt wurde. Das Schicksal der Dekabristen ist ein weiteres Zeugnis dieses Verh\u00e4ltnisses, obwohl wir uns hier nicht sonderlich von anderen totalit\u00e4ren Monarchien unterscheiden, welche die Revolution\u00e4re brutal unterdr\u00fcckten.\r\n\r\nBeispielhaft ist, dass es in der russischen Mentalit\u00e4t eine absolute Ablehnung jeglicher Reformbestrebungen vorhanden war, was ebenfalls seine Spiegelung in der Geschichte fand. Erinnern wir uns doch an den Mord an Alexander II., der vom Volk als der \u201eBefreier\u201c bezeichnet wurde, einer der wenigen Reformatoren unter den k\u00f6niglichen Pers\u00f6nlichkeiten. Und an den Mord an Stolypin, dessen Reformen Russland unter die fortschrittlichsten Demokratien Europas h\u00e4tten bringen k\u00f6nnen. Eine wichtige Besonderheit der russischen Mentalit\u00e4t war die Psychologie der Gesetzlosigkeit, das Fehlen eines Rechtsverst\u00e4ndnisses der Welt, die v\u00f6llige Ablehnung jeglicher Demokratie. Unter anderem auch deshalb\u00a0hatten die Dekabristen eine Niederlage erlitten, die nach einer konstitutionellen Monarchie strebten, wo das Gesetz \u00fcber der Macht gestanden h\u00e4tte.\r\n\r\nAlles wurde durch eine Kraft entschieden, die sich Hinterlist, Heimt\u00fccke, also T\u00e4uschung zu Diensten machte. Das sitzt sehr tief in der russischen gesellschaftlichen Psychologie, bis jetzt.\r\n\r\nDamals ist es zu einer logischen Voraussetzung f\u00fcr den Bolschewismus geworden, der eine Quintessenz von allen bis dahin existierenden imperialistischen Tendenzen gemischt mit Unrechtsbewusstsein darstellte\u00a0und der sie auf das Niveau einer sozialen Krankheit brachte. Das bolschewistische Russland stellte eine genauso kranke Gesellschaft dar wie das faschistische Deutschland.\r\n<h2 style=\"text-align: center\"><strong>Die kranke Gesellschaft<\/strong><\/h2>\r\nDer ber\u00fchmte deutsche Philosoph und Psychologe Erich Fromm, einer der Forscher der Psychologie des Totalitarismus und Faschismus, ver\u00f6ffentlichte 1955 das Buch \u201eGesunde Gesellschaft\u201c, in dem es Zeilen wie gibt: \u201eIn der Vergangenheit bestand die Gefahr darin, dass die Menschen zu Sklaven wurden. Die Gefahr der Zukunft ist, dass die Menschen zu Robotern werden k\u00f6nnen\u201c.\r\n\r\nWir neigen dazu, all die Schuld und Verantwortung auf die herrschende Schicht\u00a0zu verlegen und vergessen dabei, dass all die Gesetzlosigkeit der Anf\u00fchrer mit unserer Zustimmung geschieht. \u201eJedes Volk hat die Regierung, die es verdient,\u201c- schrieb Joseph Marie de Maistre vor zwei Jahrhunderten. Die Gesellschaft, die grausame Verbrechen innerhalb sich selbst zugelassen hatte, und diese nicht geahndet, nicht abgelehnt und nicht als eine mit der Menschlichkeit vereinbare Tat nicht verurteilt hat, kann sich nicht f\u00fcr gesund halten. Sie kann es per Definition nicht sein.\r\n\r\nIch spreche von der Krankheit der Gesellschaft, nicht nur vom politischen Regime. Denn in all den Jahren der Repressionen hat doch irgendjemand die 5 000 000\u00a0Denunziationen geschrieben, nach welchen absolut unschuldige Menschen zu Opfern geworden sind, unter fast v\u00f6lliger Duldung der absoluten Mehrheit der Menschen, vor deren Augen all das passierte. Auf der einen Seite bedeutet die Vernichtung von Millionen Menschen das Ausbluten der Nation, die ihre kl\u00fcgsten, talentiertesten, gewissenhaftesten Vertreter verliert. Auf der anderen ist es eine S\u00fcnde, ein Verbrechen, das sich im kollektiven Bewusstsein widerspiegeln m\u00fcsste.\r\n\r\nDie Bewusstwerdung dieses Verbrechens und der eigenen Beteiligung daran ist eine unbeschreiblich schwere psychologische H\u00fcrde. Eine fast unertr\u00e4gliche. Sich davor retten kann man nur auf zwei Arten. Die erste ist all das anzuerkennen und ihm eine dem Geschehen entsprechende Bewertung zu geben, indem man die Verantwortung auf sich nimmt, es verurteilt und schlie\u00dflich - es b\u00fc\u00dft. Aber auf diesem Weg entsteht ein psychologischer Widerstand: Die Angst vor dieser horrenden Scham und Schuld, die man unweigerlich erleben m\u00fcssen wird, bevor man sich davon erl\u00f6st. \u2028Der zweite Weg ist die Verneinung, die Suche nach einer Rechtfertigung, nach einer Erkl\u00e4rung f\u00fcr all das, der Aufbau eines neuen Weltbildes, das f\u00fcr jeden bequem sein wird, die Erfindung eines Ziels, um dessen willen all das getan wurde. Dabei werden die Schuld und die Scham nicht verschwinden, wie es scheinen k\u00f6nnte, aber indem sie aus dem kollektiven Bewusstsein verdr\u00e4ngt werden, werden sie im Unbewussten weiterleben. Sie werden neue Argumente und neue Taten einfordern, die das k\u00fcnstliche Weltbild der verdrehten Werte best\u00e4tigen. Sie werden neue Opfer fordern.\r\n\r\nHeute findet eine R\u00fcckkehr zum Stalinismus statt und wir erinnern uns an seine gruseligsten Seiten. Aber wir machen uns nicht immer Gedanken dar\u00fcber, warum er sich als so z\u00e4hlebig entpuppt hat. Wir m\u00f6chten uns irgendwie nicht daran erinnern, dass eine der sch\u00e4ndlichsten Seiten der russischen Geschichte das Komplott zwischen der UdSSR und Deutschland von 1937 bis 1939 und die faktische Mitwirkung an der Entfachung des Zweiten Weltkrieges ist. \u2028Damals wurde Deutschland nicht von allen als das Imperium des B\u00f6sen wahrgenommen, und die sowjetische Propaganda hat dieses gar als ein uns freundschaftlich gesinntes Land dargestellt. Erst im Juni 9141 wurde klar, mit was f\u00fcr einem Monster wir es zu tun haben. \u2028Aber das Paradoxon bestand darin, dass das stalinistische Russland in keinster Weise besser als das hitlerische Deutschland war, wenn nicht noch schlimmer, denn dieses Regime hat Dutzende Millionen seiner Mitb\u00fcrger vernichtet, was nicht mal Hitler getan hat. Und wenn die Verbrechen des Nationalismus Hitlers eine entsprechende\u00a0Bewertung von der Weltgemeinschaft und von Deutschland selbst bekommen haben, so ist der Stalinismus diesem Los entgangen. Deutschland war f\u00e4hig, diese Krankheit zu \u00fcberwinden, indem es nach dem Zweiten Weltkrieg b\u00fc\u00dfte - die UdSSR dagegen hat nicht nur keinen derartigen Versuch unternommen, sondern sich nur noch mehr auf totalit\u00e4re Positionen festgelegt . \u2028Die deutsche Aggression gegen die Sowjetunion im Juni 1941 hat faktisch zur Rehabilitierung des Bolschewismus beigetragen, als einer Ideologie eines Landes-Teilnehmers der Anti-Hitler-Koalition, das aktiv gegen Faschismus und Nazismus gek\u00e4mpft hat. An der Tagesordnung stand damals als Hauptfrage, die \u201ebraune Pest\u201c des XX. Jahrhunderts zu besiegen. Der Schaden der kommunistischen Ideologie schien dagegen nicht allzu gro\u00df zu sein. \u201e\u00dcber Sieger urteilt man nicht\u201c und \u201eDer Krieg begleicht alle Rechnungen\u201c - unter solchen Slogans ist die Krankheit aus der akuten Phase in eine chronische \u00fcbergegangen und hat sich in der gesellschaftlichen Psychologie festgesetzt (man m\u00f6chte glauben, dass dies nicht irreversibel ist...).\r\n\r\nZur Reue hat auch weder die Niederlage im Kalten Krieg noch der darauffolgende Zerfall der UdSSR gef\u00fchrt. F\u00fcr uns wurde dieser Zerfall zu etwas \u00c4hnlichem, was f\u00fcr Deutsche die Niederlage Deutschlands im Ersten Weltkrieg war. Und so, wie es in Deutschland zur Entstehung des Nazismus gef\u00fchrt hat, so haben wir in Russland nun \u00e4hnliche Resultate. Der Informationskrieg, der zur Realisation imperialistischer Ambitionen entfacht wurde, hat in erster Linie die B\u00fcrger Russlands \u00fcberfallen. Sie sind Opfer eines neuen sozialen Experiments geworden.\r\n\r\nMan kann hier folgende Schlussfolgerung ziehen:\r\n\r\n<i style=\"font-family: HelveticaNeue;color: #535353;line-height: 1.5\"><b>Die bedeutendste Folge des Informationskrieges ist die fast irreversible Transformation des gesellschaftlichen Bewusstseins eines ganzen Landes.<\/b><\/i>\r\n\r\nDer Informationskrieg hat nicht blo\u00df\u00a0zu einer propagandistischen Gehirnw\u00e4sche gef\u00fchrt. Er hat das Rezidiv einer alten Krankheit hervorgerufen, die unsere Gesellschaft vor fast 100 Jahren befallen hatte (Genauer: hat diese wieder mal aus der chronischen in eine akute Phase \u00fcberf\u00fchrt). Man kann sie verschieden nennen: Bolschewismus, Stalinismus, imperialistisches Syndrom, russischer Nazismus, orthodoxer Faschismus oder sonst wie.\r\n\r\nEs sind nicht verschiedene Erscheinungen - das sind im Grunde Symptome einer Krankheit, auch wenn sie verschiedenen Ideologien entsprungen sind, faktisch - Antipoden: kriegerischer Atheismus und kriegerische Orthodoxie, Kommunismus und Faschismus. Obwohl die Extremen, wie bekannt, zusammenfinden.\r\n\r\nAber der jetzige Rezidiv ist einer von viel schwererer Form und unterscheidet sich von der Krankheitsphase des Stalinismus durch eine deutlich erkennbare Faschistisierung des gesellschaftlichen Bewusstseins. Wie <a href=\"https:\/\/informnapalm.org\/de\/?s=Lew+SChlossberg&amp;submit=Search\">Lew Schlossberg<\/a> es treffend formulierte: <a href=\"http:\/\/inforesist.org\/segodnya-rossiya-eto-strana-idealno-gotovaya-k-fashizmu\/\">\u201eHeute ist Russland ein Land, das ideal auf Faschismus vorbereitet ist\u201c.<\/a>\r\n<h2 style=\"text-align: center\"><strong>Von Bu\u00dfe zur Heilung<\/strong><\/h2>\r\nDie Heilung von dieser Krankheit kann nur durch Bu\u00dfe geschehen. Eine tiefe und restlose Bu\u00dfe. Und diese ist ohne die Anerkennung der kollektiven Verantwortung f\u00fcr die ganze Geschichte des letzten Jahrhunderts (und vielleicht sogar noch mehr) unm\u00f6glich. Das ist eine sehr schwere Aufgabe, denn man wird durch eine gro\u00dfe Schande gehen und eine Last der schwersten Schuld auf sich nehmen m\u00fcssen. Wenn man es nicht tut, ist der einzige Weg das Scham- und Schuldgef\u00fchl zu vermeiden, die Wahrheit zu verneinen und die objektive Realit\u00e4t mit verdrehten moralischen Werten mit Hilfe von Mechanismen der projizierten Identifikation umzuf\u00e4rben.\r\n\r\nIn der Geschichte der UdSSR gab es zwei Versuche der Bu\u00dfe: w\u00e4hrend des \u201eTauwetters\u201c unter Chruschtschower und in der Zeit der Perestroika Gorbatschows. Kaum hatte sie angefangen, wurden sie jedoch schon wieder zusammengerollt, und es folgte die R\u00fcckkehr zum Stalinismus. Das erste Mal hat man die ganze Verantwortung faktisch auf Stalin geschoben und auf seine engsten hochrangigen Henker des \u201ePers\u00f6nlichkeitskults\u201c (Jeschow, Beria). Das ist wie wenn im N\u00fcrnberger Prozess nur Hitler beschuldigt worden w\u00e4re. Darum wurde der XX. Parteitag der KPdSU nicht zum N\u00fcrnberger Tribunal des Stalinismus und konnte es auch gar nicht werden. Obwohl er eine kolossale historische Bedeutung hatte (Die Rehabilitierung und Befreiung von Hunderttausenden Unschuldigen aus den Lagern), war es eine unvollendete Heilung, die sp\u00e4ter zu Rezidiven f\u00fchrte.\r\n\r\nEchte Reue kam auch nicht w\u00e4hrend der Perestroika-Zeit auf, obwohl die Hoffnung bestand, dass es so sein wird. Unvollst\u00e4ndige Bu\u00dfe wird keine Befreiung bringen. Sie ist wie ein nicht komplett herausgeschnittenes Krebsgeschw\u00fcr, das neue Metastasen bilden kann und den scheinbar geheilten Organismus mit einer neuen Krankheit befallen kann, manchmal sogar schwerer als der zuvor. Und wenn man das Unkraut nicht mit der Wurzel herausrei\u00dft, wird es wieder auskeimen und die Nutzpflanzen t\u00f6ten.\r\n\r\nDie parallele Realit\u00e4t, die durch die Kremlpropaganda erschaffen wurde, ist ein wunderbarer psychologischer Schutz vor dem traumatisierten Bewusstsein des Aggressors, das ist eine Erl\u00f6sung von der Notwendigkeit der Bu\u00dfe, von der \u00dcbernahme der Verantwortung, vom Schulderleben und jeglichen anderen Regungen des Gewissens. Die Schande der Bewusstwerdung der Ungeheuerlichkeit der zu rechtfertigenden Verbrechen kann man stolz\u00a0mit \u201eOpas haben gek\u00e4mpft\u201c und \u201eAufstehen von den Knien\u201c, mit\u00a0Erhabenheit der \u201eRussischen Welt\u201c und anderen Mythen ersetzen, die aus der parallelen Antiwelt andere Realit\u00e4ten verdr\u00e4ngen, die wegen ihrer scheu\u00dflichen Wahrheit nicht zu ertragen sind.\r\n\r\nDie deutsche Nation ist da durchgegangen, auch wenn es ihr ganz und gar nicht leicht gefallen ist. Dieser Prozess endete nicht mit N\u00fcrnberg und erstreckte sich auf mehrere Jahrzehnte.\u00a0Die niederschmetternde Niederlage im Zweiten Weltkrieg, seine\u00a0nationale Trag\u00f6die, hat\u00a0Deutschland, wie paradox es auch ist, dabei geholfen. Braucht\u00a0denn Russland nicht auch eine nicht weniger niederschmetternde Niederlage, um derartiges Fegefeuer durchzustehen?\r\n\r\nWenn man nach dem Geschehen der letzten Monate urteilt, wird genau so ein Szenario absolut wahrscheinlich.\r\n\r\n* * *\r\n\r\nWie kann man dem katastrophalen Geschehen vorbeugen, um so mehr - der Gefahr einer thermonuklearen Weltkatastrophe? Wie kann man den Informations-Frankenstein aufhalten? Und ist es \u00fcberhaupt m\u00f6glich?\r\n\r\nMan muss etwas im Bewusstsein der Menschen \u00e4ndern, sie zwingen zu verstehen, dass die Medienpropagandisten die realen Schuldigen an den tragischen Ereignissen sind, die unter der Einwirkung der Propaganda stattfinden, und dass sie mit Kriegsverbrechern gleichgesetzt werden m\u00fcssen. Man muss die ungesunde kollektive Psyche der Gesellschaft heilen, die parallelen Realit\u00e4ten transformieren, die\u00a0im Stande sind, Menschen massenhaft zu t\u00f6ten.\r\n\r\nDiese Aufgaben sind nicht weniger wichtig, als die Probleme der Bewaffnung, die wirtschaftlichen Reformen, der Kampf mit der Korruption. Dar\u00fcber m\u00fcssen sich die Politiker und die Wissenschaftler (in erster Linie- soziale und politische Psychologen) den Kopf zerbrechen. Aber daf\u00fcr braucht man wenigstens die Entstehung eines Bedarfs nach ihrer L\u00f6sung.\r\n\r\nAll die Gespr\u00e4che dar\u00fcber, dass es noch \u201enicht an der Zeit\u201c ist, dass es wichtigere Aufgaben gibt, sind belanglos, denn ohne die fachm\u00e4nnische Informationspolitik wird die L\u00f6sung der wichtigen Staatsaufgaben unm\u00f6glich und wird viel gr\u00f6\u00dfere Ressourcen einfordern. All die \u00dcberlegungen dar\u00fcber, dass wir keine Mittel dazu haben sind verbrecherisch gef\u00e4hrlich. Das Ausbleiben\u00a0dieses Vorgehens wird uns tausend Mal mehr kosten.\r\n\r\nK\u00fcrzlich\u00a0wurde ein Informationsministerium geschaffen, in dem eine Abteilung f\u00fcr Informationssicherheit gebildet wurde (na endlich!). Es scheint, als ob die Sache in Schwung gekommen ist. Aber diese Beh\u00f6rde besch\u00e4ftigt sich \u00fcberhaupt nicht mit den Problemen der Medienraum-Psychologie, sie verstehen nicht, dass dies die Schl\u00fcsselprobleme sind, denn die Parallelrealit\u00e4ten existieren in der Psyche der Menschen. Aber noch interessanter ist der Fakt, dass es \u00e4hnliche Strukturen auch fr\u00fcher schon gab: Das ist die Abteilung f\u00fcr Informationspolitik des Au\u00dfenministeriums der Ukraine und den Rat f\u00fcr Fragen der Informationspolitik beim Pr\u00e4sidenten der Ukraine, wie auch die Abteilung f\u00fcr Informationssicherheit beim SBU, die schon 2011 schaffen wurde. Was haben sie denn bis jetzt gemacht?\r\n\r\nMan muss verstehen, dass der Informationskrieg bereits seit 15 Monaten l\u00e4uft. Und auf einen Krieg muss man mit ad\u00e4quaten Mitteln antworten. Man muss ununterbrochen gegen die Desinformation k\u00e4mpfen, indem man die parallele Realit\u00e4t der informativen Antiwelt zerst\u00f6rt. Aber die Gegenpropaganda darf nicht dieselben Waffen verwenden.\r\n\r\nDer L\u00fcge muss man die Wahrheit entgegenstellen. Man muss verstehen (und das ist sehr erfreulich), dass die Desinformation, die in einem Informationskrieg die Hauptwaffe ist, eine \u201eschnellverderbliche\u201c Ware ist. Mit der Zeit, unter dem Druck der Wahrheit, oder sogar einfach nur unter dem Druck des gesunden Menschenverstandes, geschieht ihr nat\u00fcrlicher \u201eHalbzerfall\u201c. Man muss sie permanent mit einer neuen ersetzen, darum braucht man immer neuere Geschichten, Videos, \u201eZeugnisse\u201c der Pseudozeugen. Die Wahrheit dagegen, die man der L\u00fcge entgegenstellen kann, hat faktisch eine unbegrenzte Haltbarkeit. Mehr noch, wenn es die Pr\u00fcfung der Zeit besteht, wird es, wie ein guter Wein oder Cognac, noch besser und robuster.\r\n\r\nFr\u00fcher oder sp\u00e4ter wird die Wahrheit siegen und die parallele Realit\u00e4t zerst\u00f6ren. Und je grandioser die Konstruktion war, um so niederschmetternder wird die Katastrophe. Und auf den Tr\u00fcmmern der alten \u201einformativen Antiwelt\u201c wird eine neue lebendige Realit\u00e4t aufkeimen, so wie einst auf den Tr\u00fcmmern des infolge von L\u00fcge und Unzucht untergegangenen R\u00f6mischen Imperiums eine neue Europ\u00e4ische Zivilisation entstand.\r\n\r\n<hr \/>\r\n\r\n<em>Autor: <strong><a href=\"https:\/\/www.facebook.com\/pavelgorn\">Pawel Gornostai<\/a><\/strong>, Dr. der Psychologiewissenschaften; <a href=\"http:\/\/gorn.kiev.ua\">Website des Autors<\/a>; \u00fcbersetzt von <a href=\"https:\/\/www.facebook.com\/Kaspijka\">Irina Schlegel.<\/a><\/em>","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/3933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/comments?post=3933"}],"version-history":[{"count":33,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/3933\/revisions"}],"predecessor-version":[{"id":25890,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/posts\/3933\/revisions\/25890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/media\/3935"}],"wp:attachment":[{"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/media?parent=3933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/categories?post=3933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informnapalm.org\/de\/wp-json\/wp\/v2\/tags?post=3933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}